{"id":10579,"date":"2023-01-06T04:24:48","date_gmt":"2023-01-06T04:24:48","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=10579"},"modified":"2023-01-06T04:24:50","modified_gmt":"2023-01-06T04:24:50","slug":"impulsa-leticia-herrera-colaboracion-con-empresas-para-dar-empleo-a-gomezpalatinas","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/01\/06\/impulsa-leticia-herrera-colaboracion-con-empresas-para-dar-empleo-a-gomezpalatinas\/","title":{"rendered":"<em>Impulsa Leticia Herrera colaboraci\u00f3n con empresas para dar empleo a gomezpalatinas<\/em>"},"content":{"rendered":"\n<p>Por Instrucciones de la Presidenta Municipal, Leticia Herrera Ale, el Instituto Municipal de la Mujer, continuando haciendo las gestiones necesarias para ayudar a las mujeres en su empoderamiento, trabajando en esta ocasi\u00f3n con empresas locales para brindarle espacios laborales a este sector de la poblaci\u00f3n, como es el caso de la relaci\u00f3n entablada con la empresa VAGALU<br>Lo Anterior lo dio a conocer la titular del mencionado instituto, Myrna Leticia Soto Soto, quien menciono que la prioridad de la presidenta municipal es muy clara y que, con base en esa visi\u00f3n y recomendaciones se ha estado trabajando durante el tiempo transcurrido de esta administraci\u00f3n.<br>\u201cPara la presidenta Leticia Herrera Ale, es importante fortalecer el empoderamiento econ\u00f3mico de las mujeres, por lo que a trav\u00e9s de este instituto y en coordinaci\u00f3n con el sector empresarial, hemos logrado esta colaboraci\u00f3n con distintas vacantes\u201d, apunt\u00f3.<br>Explic\u00f3 que la empresa Soluciones y Log\u00edstica VAGALU ofrece lo siguiente: bono de productividad, sueldo base con bono, pago semanal, turnos fijos, seguro social, vacaciones, contrataci\u00f3n sin l\u00edmite de edad a partir de los 18 a\u00f1os, prestaciones de ley y, un punto importante es que no se necesita experiencia para tener una oportunidad laboral en esta empresa.<br>Finalmente, Leticia Soto anunci\u00f3 que las mujeres que est\u00e9n interesadas en ser parte de esta empresa, deber\u00e1 acudir a las oficinas del IMM con su Clave \u00danica del Registro de Poblaci\u00f3n (CURP) y el Registro Federal del Contribuyente (RFC), en el lugar, se les dar\u00e1 la atenci\u00f3n debida para dicho proceso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Instrucciones de la Presidenta Municipal, Leticia Herrera Ale, el Instituto Municipal de la Mujer, continuando haciendo las gestiones necesarias para ayudar a las mujeres en su empoderamiento, trabajando en esta ocasi\u00f3n con empresas locales para brindarle espacios laborales a este sector de la poblaci\u00f3n, como es el caso de la relaci\u00f3n entablada con la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10580,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10579"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10579"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10579\/revisions"}],"predecessor-version":[{"id":10581,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10579\/revisions\/10581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/10580"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}