{"id":10662,"date":"2023-01-07T00:02:35","date_gmt":"2023-01-07T00:02:35","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=10662"},"modified":"2023-01-07T00:02:37","modified_gmt":"2023-01-07T00:02:37","slug":"anuncia-homero-martinez-adquisicion-de-nuevo-parque-vehicular","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/01\/07\/anuncia-homero-martinez-adquisicion-de-nuevo-parque-vehicular\/","title":{"rendered":"<em>ANUNCIA HOMERO MART\u00cdNEZ ADQUISICI\u00d3N DE NUEVO PARQUE VEHICULAR<\/em>"},"content":{"rendered":"\n<p>Lerdo, 06 enero 2023.- El Presidente Municipal Homero Mart\u00ednez Cabrera, anunci\u00f3 la adquisici\u00f3n de un nuevo parque vehicular para las dependencias de Recolecci\u00f3n de Basura, Tr\u00e1nsito y Vialidad, con lo que se garantizar\u00e1 la prestaci\u00f3n de los servicios p\u00fablicos, con una inversi\u00f3n propia, proveniente de los ingresos del Ayuntamiento.<\/p>\n\n\n\n<p>El Alcalde resalt\u00f3 que la adquisici\u00f3n de unidades para la direcci\u00f3n de Servicios P\u00fablicos, permitir\u00e1 eficientizar la recolecci\u00f3n de basura en las villas del Municipio, asignando una unidad permanente en cada una de ellas, as\u00ed como la construcci\u00f3n de un relleno sanitario propio, para ahorrar gastos de traslado hasta la cabecera municipal.<\/p>\n\n\n\n<p>Por \u00faltimo, se\u00f1al\u00f3 que se ha concretado un convenio de participaci\u00f3n con Grupo SIMSA, para la donaci\u00f3n de una patrulla a la direcci\u00f3n de Seguridad P\u00fablica, demostrando el compromiso mutuo de esta empresa hacia los intereses del gobierno municipal con el objetivo de salvaguardar el bienestar de las familias, e hizo \u00e9nfasis en que se contin\u00faan sosteniendo di\u00e1logos con los empresarios de la ciudad, para una mayor aportaci\u00f3n.<\/p>\n\n\n\n<p>Cabe destacar que en el mes de noviembre del a\u00f1o pasado, el Gobernador del estado de Durango Esteban Villegas junto al Alcalde de Lerdo Homero Mart\u00ednez, hicieron la entrega de un parque vehicular a la Direcci\u00f3n de Seguridad P\u00fablica Municipal, conformado por dos patrullas, una cuatrimoto y diez motocicletas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lerdo, 06 enero 2023.- El Presidente Municipal Homero Mart\u00ednez Cabrera, anunci\u00f3 la adquisici\u00f3n de un nuevo parque vehicular para las dependencias de Recolecci\u00f3n de Basura, Tr\u00e1nsito y Vialidad, con lo que se garantizar\u00e1 la prestaci\u00f3n de los servicios p\u00fablicos, con una inversi\u00f3n propia, proveniente de los ingresos del Ayuntamiento. El Alcalde resalt\u00f3 que la adquisici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10662"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10662"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10662\/revisions"}],"predecessor-version":[{"id":10664,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/10662\/revisions\/10664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/10663"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}