{"id":12826,"date":"2023-02-20T00:20:11","date_gmt":"2023-02-20T00:20:11","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=12826"},"modified":"2023-02-20T00:20:16","modified_gmt":"2023-02-20T00:20:16","slug":"instituto-coahuilense-de-las-mujeres-brinda-platica-en-secundaria-de-saltillo","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/02\/20\/instituto-coahuilense-de-las-mujeres-brinda-platica-en-secundaria-de-saltillo\/","title":{"rendered":"<strong>INSTITUTO COAHUILENSE DE LAS MUJERES BRINDA PL\u00c1TICA EN SECUNDARIA DE SALTILLO<\/strong>"},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 18 de Febrero de 2023. \u2013 Con la finalidad de prevenir y atender la violencia contra las mujeres, el Gobierno del Estado, que encabeza Miguel \u00c1ngel Riquelme Sol\u00eds, a trav\u00e9s de su Secretaria de Gobierno y el Instituto Coahuilense de las Mujeres, implementa diversas estrategias.&nbsp;<\/p>\n\n\n\n<p>Katy Salinas P\u00e9rez, titular del Instituto Coahuilense de las Mujeres, se\u00f1al\u00f3 que personal de la Direcci\u00f3n de Capacitaci\u00f3n brind\u00f3 una pl\u00e1tica sobre relaciones afectivas dirigida a alumnas y alumnos de la Escuela Secundaria No. 32.&nbsp;<\/p>\n\n\n\n<p>Durante el desarrollo de la pl\u00e1tica se brind\u00f3 informaci\u00f3n a las y los estudiantes sobre los derechos humanos, los tipos de violencia contra las mujeres y sus modalidades, as\u00ed como el \u201cABC de g\u00e9nero\u201d.<\/p>\n\n\n\n<p>\u201cEs importante que las y los j\u00f3venes identifiquen los tipos de violencia que pueden presentarse, sobre todo en las relaciones, pues la violencia contra las mujeres ha sido normalizada e invisibilizada por generaciones, lo que ocasiona encontrarse en un c\u00edrculo de violencia\u201d, mencion\u00f3 Salinas P\u00e9rez.<\/p>\n\n\n\n<p>Adem\u00e1s, se les proporcion\u00f3 informaci\u00f3n de las diversas instituciones especializadas en la atenci\u00f3n a la violencia contra las mujeres, a las cuales se pueden acercar a solicitar apoyo.<\/p>\n\n\n\n<p>-o0o-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 18 de Febrero de 2023. \u2013 Con la finalidad de prevenir y atender la violencia contra las mujeres, el Gobierno del Estado, que encabeza Miguel \u00c1ngel Riquelme Sol\u00eds, a trav\u00e9s de su Secretaria de Gobierno y el Instituto Coahuilense de las Mujeres, implementa diversas estrategias.&nbsp; Katy Salinas P\u00e9rez, titular del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12826"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=12826"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12826\/revisions"}],"predecessor-version":[{"id":12828,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12826\/revisions\/12828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/12827"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=12826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=12826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=12826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}