{"id":12834,"date":"2023-02-21T02:06:57","date_gmt":"2023-02-21T02:06:57","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=12834"},"modified":"2023-02-21T02:07:00","modified_gmt":"2023-02-21T02:07:00","slug":"ponen-en-marcha-ciclo-escolar-en-el-conalep-de-torreon","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/02\/21\/ponen-en-marcha-ciclo-escolar-en-el-conalep-de-torreon\/","title":{"rendered":"<strong>Ponen en marcha ciclo escolar en el CONALEP de Torre\u00f3n<\/strong>"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 20 de febrero de 2023.<\/p>\n\n\n\n<p>El Alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez y el Gobernador de Coahuila Miguel \u00c1ngel Riquelme Sol\u00eds, pusieron en marcha el ciclo escolar 2022 &#8211; 2023 en el CONALEP Torre\u00f3n, en donde tambi\u00e9n se hizo entrega de equipo y se firm\u00f3 un convenio de colaboraci\u00f3n con la COPARMEX Laguna.<\/p>\n\n\n\n<p>El Presidente Municipal coment\u00f3 que para su Gobierno es importante que los estudiantes acudan a escuelas en buenas condiciones, y agreg\u00f3 que el a\u00f1o pasado se invirtieron alrededor de 13 millones de pesos en planteles que necesitaban mejoramiento o rehabilitaci\u00f3n.<\/p>\n\n\n\n<p>\u201cEl que tengamos una comunidad estudiantil comprometida, como lo hace el CONALEP es importante, el que todos los \u00f3rdenes de Gobierno tengamos como meta la educaci\u00f3n, es parte importante para tener una sociedad m\u00e1s justa, equitativa, responsable y mejor preparada\u201d, expres\u00f3 el edil.<\/p>\n\n\n\n<p>En su mensaje, destac\u00f3 tambi\u00e9n la importancia de la educaci\u00f3n, la formaci\u00f3n y el contar con planteles dignos y equipados para los j\u00f3venes.<\/p>\n\n\n\n<p>Rom\u00e1n Alberto Cepeda Gonz\u00e1lez dijo que seguir\u00e1 trabajando de manera coordinada con el Gobierno del Estado para la generaci\u00f3n de m\u00e1s y mejores empleos.<\/p>\n\n\n\n<p>Miguel \u00c1ngel Riquelme Sol\u00eds, Gobernador del Estado, dio inicio formal al ciclo escolar en el CONALEP Torre\u00f3n, y expres\u00f3 su agradecimiento por la colaboraci\u00f3n del Alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez en el rubro educativo.<\/p>\n\n\n\n<p>\u201cHoy ustedes tienen un gran futuro que se ha construido entre todos, est\u00e1n estudiando, se est\u00e1n capacitando y tienen mejores herramientas, pero van a tener lo mejor, que es trabajar aqu\u00ed en su tierra\u201d, coment\u00f3 el mandatario.<\/p>\n\n\n\n<p>Dijo que los estudiantes son lo m\u00e1s importante para el presente y el futuro de Coahuila.<\/p>\n\n\n\n<p>Alfio Vega de la Pe\u00f1a, Director General del CONALEP Coahuila, indic\u00f3 que son m\u00e1s de 10 mil alumnos los que regresan a clases en la instituci\u00f3n en todo el estado, por lo que durante las primeras semanas del a\u00f1o se procedi\u00f3 con acciones para mantener los planteles en condiciones dignas y actualizados.<\/p>\n\n\n\n<p>Habl\u00f3 de la importancia de la cooperaci\u00f3n entre el CONALEP y la Iniciativa Privada, en favor de sus estudiantes, por lo que dijo que el convenio firmado con COPARMEX va en el sentido de favorecer al estudiantado con la vinculaci\u00f3n empresarial.<\/p>\n\n\n\n<p>Durante la firma del convenio de colaboraci\u00f3n, el Gobernador Miguel \u00c1ngel Riquelme Sol\u00eds y el Alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, fungieron como testigos de honor.<\/p>\n\n\n\n<p>Por su parte, Jorge Leopoldo Reyes Casas, presidente de COPARMEX Laguna, dijo que con la firma de convenios como este, los j\u00f3venes tienen mayores oportunidades de integrarse a las industrias y a las empresas de una manera mucho m\u00e1s ordenada.<\/p>\n\n\n\n<p>En el acto se hizo entrega de una maquina fresadora para la carrera de m\u00e1quinas herramientas, as\u00ed como ejemplares para el programa \u201cAbre tu libro\u201d y uniforme para el equipo de rob\u00f3tica.<\/p>\n\n\n\n<p>Acudieron al evento Ver\u00f3nica Mart\u00ednez Garc\u00eda, Senadora de la Rep\u00fablica; Jos\u00e9 Antonio Guti\u00e9rrez Jard\u00f3n, Diputado Federal; Mario Cepeda Ram\u00edrez, Diputado Local; Francisco Saracho Navarro, Secretario de Educaci\u00f3n del Estado; as\u00ed como Irma Mayela Adame Aguayo, directora del CONALEP Torre\u00f3n.<\/p>\n\n\n\n<p><em>&#8211;&nbsp; Torre\u00f3n \u00a1Siempre Puede! &#8211;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 20 de febrero de 2023. El Alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez y el Gobernador de Coahuila Miguel \u00c1ngel Riquelme Sol\u00eds, pusieron en marcha el ciclo escolar 2022 &#8211; 2023 en el CONALEP Torre\u00f3n, en donde tambi\u00e9n se hizo entrega de equipo y se firm\u00f3 un convenio de colaboraci\u00f3n con la COPARMEX Laguna. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12834"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=12834"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12834\/revisions"}],"predecessor-version":[{"id":12836,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12834\/revisions\/12836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/12835"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=12834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=12834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=12834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}