{"id":12838,"date":"2023-02-21T02:10:00","date_gmt":"2023-02-21T02:10:00","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=12838"},"modified":"2023-02-21T02:10:08","modified_gmt":"2023-02-21T02:10:08","slug":"revisan-lonas-y-espectaculares-por-temporada-de-viento-y-tolvaneras","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/02\/21\/revisan-lonas-y-espectaculares-por-temporada-de-viento-y-tolvaneras\/","title":{"rendered":"<strong>Revisan lonas y espectaculares por temporada de viento y tolvaneras<\/strong>"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 20 de febrero de 2023.<\/p>\n\n\n\n<p>Como parte de las medidas preventivas que coordina la Direcci\u00f3n de Protecci\u00f3n Civil y Bomberos de Torre\u00f3n, para proteger la seguridad de la poblaci\u00f3n, se convoc\u00f3 a propietarios de lonas y espectaculares para establecer las indicaciones que deben seguir en cuanto al mantenimiento de las estructuras, o en caso de riesgo, proceder a su retiro.<\/p>\n\n\n\n<p>A\u00fan y cuando son los meses de febrero y marzo cuando suceden m\u00e1s com\u00fanmente eventos de viento en la regi\u00f3n, el titular de la dependencia, Jorge Luis Ju\u00e1rez Llanas, dijo que desde enero se presentaron algunos frentes fr\u00edos con tolvaneras, por lo que inici\u00f3 con la revisi\u00f3n de lonas y el llamado a los concesionarios a corregir los se\u00f1alamientos hechos por la direcci\u00f3n.<\/p>\n\n\n\n<p>Siguiendo con las pr\u00e1cticas implementadas en la Administraci\u00f3n del Alcalde Rom\u00e1n Alberto Cepeda de prevenir incidentes y actuar con anticipaci\u00f3n fue que se procedi\u00f3 con dichos trabajos.<\/p>\n\n\n\n<p>\u201cQueremos anticiparnos para la temporada m\u00e1s fuerte de vientos y tolvaneras, inspeccionar que est\u00e9n bien sujetas las lonas, que no pongan en riesgo a la ciudadan\u00eda\u201d, coment\u00f3 el funcionario.<\/p>\n\n\n\n<p>Con ese fin y aprovechando tambi\u00e9n que la direcci\u00f3n debe dar su visto bueno para que los publicistas realicen el tr\u00e1mite de renovaci\u00f3n de la licencia, es como se ha procedido para la inspecci\u00f3n.<\/p>\n\n\n\n<p>Adem\u00e1s, asegurarse que no haya desprendimiento o un mal estado en las lonas, impacta tambi\u00e9n al momento de una eventualidad, pues cuando se registra la tolvanera o r\u00e1faga de viento, resulta peligroso tambi\u00e9n para el personal de Protecci\u00f3n Civil y Bomberos que tiene que subir a las alturas para atender la emergencia.<\/p>\n\n\n\n<p>Una vez que se hizo el llamado a los proveedores de publicidad para que atiendan a las recomendaciones de la direcci\u00f3n, de hacer caso omiso se procede a una multa o en cese definitivo de la concesi\u00f3n por parte de la Direcci\u00f3n de Ordenamiento Territorial y Urbanismo.<\/p>\n\n\n\n<p>Sin embargo, Ju\u00e1rez Llanas asever\u00f3 que hasta el momento, han tenido buena recepci\u00f3n por parte de los involucrados, que han atendido a las indicaciones en cuanto a lonas, l\u00e1minas y anuncios que tienen colocados en la ciudad.<\/p>\n\n\n\n<p>Finalmente exhort\u00f3 a la ciudadan\u00eda a reportar alg\u00fan anuncio o lona que detecten como de riesgo, as\u00ed como evitar pasar o estacionarse cerca de este tipo de estructuras en caso de r\u00e1fagas de viento de consideraci\u00f3n.<\/p>\n\n\n\n<p>La l\u00ednea de contacto de la Direcci\u00f3n de Protecci\u00f3n Civil y Bomberos es el tel\u00e9fono 871 712 00 66.<\/p>\n\n\n\n<p><em>&#8211;&nbsp; Torre\u00f3n \u00a1Siempre Puede! &#8211;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 20 de febrero de 2023. Como parte de las medidas preventivas que coordina la Direcci\u00f3n de Protecci\u00f3n Civil y Bomberos de Torre\u00f3n, para proteger la seguridad de la poblaci\u00f3n, se convoc\u00f3 a propietarios de lonas y espectaculares para establecer las indicaciones que deben seguir en cuanto al mantenimiento de las estructuras, o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12838"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=12838"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12838\/revisions"}],"predecessor-version":[{"id":12840,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/12838\/revisions\/12840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/12839"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=12838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=12838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=12838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}