{"id":14171,"date":"2023-03-14T23:45:03","date_gmt":"2023-03-14T23:45:03","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=14171"},"modified":"2023-03-14T23:45:14","modified_gmt":"2023-03-14T23:45:14","slug":"residuos-de-poda-solo-se-recibiran-en-el-relleno-sanitario","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/03\/14\/residuos-de-poda-solo-se-recibiran-en-el-relleno-sanitario\/","title":{"rendered":"<em>Residuos de poda solo se recibir\u00e1n en el relleno sanitario<\/em>"},"content":{"rendered":"\n<p><em>Se cierran centros de transferencia<\/em><\/p>\n\n\n\n<p>El Ayuntamiento de G\u00f3mez Palacio, a trav\u00e9s de la Direcci\u00f3n de Ecolog\u00eda y Protecci\u00f3n Ambiental, informa que, el \u00fanico espacio permitido en el municipio para depositar los residuos de poda y tala de \u00e1rboles, es el relleno sanitario.<\/p>\n\n\n\n<p>Por esta raz\u00f3n, todas aquellas personas que originen residuos de poda y tala de \u00e1rboles, deber\u00e1n trasladarlos, o asegurarse de que quienes les ofrezcan el servicio de traslado lo lleven hasta el relleno sanitario ubicado en la carretera a San Gerardo, en el Ejido San Ram\u00f3n.<\/p>\n\n\n\n<p>Carlos Rosales Arcaute, titular de la citada dependencia, coment\u00f3 que la temporada de poda libre ya concluy\u00f3, y del mes de marzo en adelante todos quienes deseen realizar ese tipo de intervenciones en sus \u00e1rboles tendr\u00e1n que solicitar ante la direcci\u00f3n municipal de ecolog\u00eda, ubicada al interior del parque La Esperanza, el permiso para realizarlo.<\/p>\n\n\n\n<p>El permiso no tiene costo, sin embargo, debe llevarse a cabo una supervisi\u00f3n y si, la dependencia dictamina que es procedente, se concede la autorizaci\u00f3n para efectuar la poda o tala.<\/p>\n\n\n\n<p>Sobre los residuos generados por la poda o tala, Rosales Arcaute coment\u00f3 que si los inspectores del \u00e1rea a su cargo detectan ramas y troncos a exterior de alguna vivienda, ser\u00e1n notificados y contar\u00e1n con un plazo de 24 horas para trasladar dichos residuos al relleno sanitario, mismo que estar\u00e1 operando de lunes a domingo, de 7:00 de la ma\u00f1ana a 10:00 de la noche.<\/p>\n\n\n\n<p>Con respecto a los centros de transferencia, el funcionario coment\u00f3 que estos ya fueron cerrados, y desde hace d\u00edas, se ha trabajado de manera muy ardua en su limpieza, sobre un nuevo centro de transferencia. Rosales Arcaute, coment\u00f3 que est\u00e1n en la b\u00fasqueda de una espacio adecuado para esta finalidad. .<\/p>\n\n\n\n<p>Finalmente, coment\u00f3 que, de hacer caso omiso a las indicaciones interpuestas por los inspectores, la persona podr\u00e1 ser acreedora a una multa que va de las 20 a 40 UMA\u00b4s, seg\u00fan sea el da\u00f1o ecol\u00f3gico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se cierran centros de transferencia El Ayuntamiento de G\u00f3mez Palacio, a trav\u00e9s de la Direcci\u00f3n de Ecolog\u00eda y Protecci\u00f3n Ambiental, informa que, el \u00fanico espacio permitido en el municipio para depositar los residuos de poda y tala de \u00e1rboles, es el relleno sanitario. Por esta raz\u00f3n, todas aquellas personas que originen residuos de poda y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14171"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=14171"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14171\/revisions"}],"predecessor-version":[{"id":14173,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14171\/revisions\/14173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/14172"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=14171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=14171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=14171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}