{"id":14185,"date":"2023-03-14T23:57:07","date_gmt":"2023-03-14T23:57:07","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=14185"},"modified":"2023-03-14T23:57:11","modified_gmt":"2023-03-14T23:57:11","slug":"fortalece-ayuntamiento-de-gomez-palacio-a-organizaciones-de-la-sociedad-civil","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/03\/14\/fortalece-ayuntamiento-de-gomez-palacio-a-organizaciones-de-la-sociedad-civil\/","title":{"rendered":"<em>Fortalece Ayuntamiento de G\u00f3mez Palacio a Organizaciones de la Sociedad Civil<\/em>"},"content":{"rendered":"\n<p><em>55 asociaciones se comprometen a redoblar esfuerzos por los gomezpalatinos.<\/em><\/p>\n\n\n\n<p>En el marco de la b\u00fasqueda permanente que la alcaldesa de G\u00f3mez Palacio, Leticia Herrera Ale, tiene por establecer alianzas con diversos sectores de la poblaci\u00f3n, para que se sumen en la construcci\u00f3n de un mejor G\u00f3mez Palacio, 55 asociaciones civiles se comprometieron a redoblar esfuerzos y seguir trabajando por los gomezpalatinos.<\/p>\n\n\n\n<p>Al medio d\u00eda de hoy, la alcaldesa de G\u00f3mez Palacio, realiz\u00f3 la entrega simb\u00f3lica de cheques a 55 asociaciones civiles que atendieron a la convocatoria \u201cAsociaciones con Estrella\u201d, realizada el pasado mes de enero, a trav\u00e9s de la Direcci\u00f3n de Bienestar Social, para inscribirse en el padr\u00f3n de asociaciones que recibir\u00e1n apoyo econ\u00f3mico por parte de la administraci\u00f3n municipal.<\/p>\n\n\n\n<p>Con una inversi\u00f3n municipal total de 3 millones de pesos que se distribuir\u00e1n entre las asociaciones que cumplieron con la integraci\u00f3n de sus expedientes conforme a la convocatoria, ser\u00e1 dividido el apoyo en 9 ministraciones de 333 mil pesos efectuadas entre marzo y noviembre del presente a\u00f1o.<\/p>\n\n\n\n<p>Eduardo Faudoa Ch\u00e1vez, director de Bienestar Social en el municipio, explic\u00f3 durante la exposici\u00f3n de motivos que el objetivo de acciones como esta es reafirmar el compromiso de trabajo que cada uno de los presentes tiene para con la sociedad gomezpalatina \u201csigamos trabajando por nuestro municipio, especialmente por los m\u00e1s vulnerables\u201d.<\/p>\n\n\n\n<p>En su mensaje, Leticia Herrera expres\u00f3 a las asociaciones presentes \u201cReconozco desde siempre el trabajo de todas y cada una de ustedes el hacer de su vida una labor incansable en beneficio de todos, es invaluable el trabajo extraordinario que realizan para construir una mejor sociedad\u201d.<\/p>\n\n\n\n<p>\u201cQuiero decirles, que en mi Gobierno estamos comprometidos con las organizaciones de la sociedad civil y por ello estamos aqu\u00ed; para comprometernos mutuamente y ayudarles a potenciar su noble labor, pero sobre todo, para que sientan el respaldo de este gobierno\u201d. Expres\u00f3 la primera autoridad de G\u00f3mez Palacio.<br>Entre las asociaciones civiles que integran el padr\u00f3n de beneficiarias del programa \u201cAsociaciones con Estrella\u201d destacan las que se dedican a atender necesidades de la comunidad en los siguientes rubros:<br>Asistencial, art\u00edstico, de atenci\u00f3n mental, centros de rehabilitaci\u00f3n, impulso al deporte, acompa\u00f1amiento tanatol\u00f3gico, dispensarios, educaci\u00f3n especial, empoderamiento de la mujer, desarrollo de habilidades productivas de la mujer, agro empresarial, ambiental, entre muchos otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>55 asociaciones se comprometen a redoblar esfuerzos por los gomezpalatinos. En el marco de la b\u00fasqueda permanente que la alcaldesa de G\u00f3mez Palacio, Leticia Herrera Ale, tiene por establecer alianzas con diversos sectores de la poblaci\u00f3n, para que se sumen en la construcci\u00f3n de un mejor G\u00f3mez Palacio, 55 asociaciones civiles se comprometieron a redoblar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14185"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=14185"}],"version-history":[{"count":2,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14185\/revisions"}],"predecessor-version":[{"id":14188,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14185\/revisions\/14188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/14186"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=14185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=14185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=14185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}