{"id":14198,"date":"2023-03-15T00:03:36","date_gmt":"2023-03-15T00:03:36","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=14198"},"modified":"2023-03-15T00:03:39","modified_gmt":"2023-03-15T00:03:39","slug":"unidad-municipal-de-derechos-humanos-mantiene-acciones-permanentes-en-atencion-a-los-migrantes","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/03\/15\/unidad-municipal-de-derechos-humanos-mantiene-acciones-permanentes-en-atencion-a-los-migrantes\/","title":{"rendered":"<strong>Unidad Municipal de Derechos Humanos mantiene acciones permanentes en atenci\u00f3n a los migrantes.<\/strong>"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 14 de marzo de 2023.<\/p>\n\n\n\n<p>La Unidad Municipal de Derechos Humanos (UMDH) de Torre\u00f3n en coordinaci\u00f3n con otras dependencias y asociaciones civiles, desarrolla acciones permanentes en atenci\u00f3n a los migrantes que est\u00e1n de paso por la ciudad, as\u00ed lo inform\u00f3 Miguel \u00c1ngel Urrutia de la Torre, titular de la dependencia a ediles integrantes de la comisi\u00f3n que lo supervisa.<\/p>\n\n\n\n<p>El funcionario se\u00f1al\u00f3 que durante el mes de enero y febrero la Unidad fungi\u00f3 como ente observador y acompa\u00f1ante de los migrantes durante el operativo invernal en el que participaron las Direcciones de Seguridad P\u00fablica, Protecci\u00f3n Civil y Bomberos, as\u00ed como Salud Municipal, entre otras.<\/p>\n\n\n\n<p>En ese sentido agreg\u00f3 que los esfuerzos por mantener un v\u00ednculo cercano con las asociaciones civiles que velan por el bienestar de los migrantes contin\u00faan, desarrollando as\u00ed una agenda de trabajo que incluye la impartici\u00f3n de una capacitaci\u00f3n a elementos de Seguridad P\u00fablica, sobre el trato y manejo de situaciones que involucren a este sector de la poblaci\u00f3n, misma que habr\u00e1 de realizarse la pr\u00f3xima semana.<\/p>\n\n\n\n<p>Agreg\u00f3 que contar con el testimonio de los migrantes durante las pl\u00e1ticas, abonar\u00e1 a la socializaci\u00f3n y entendimiento de la problem\u00e1tica por la que atraviesan estas personas.<\/p>\n\n\n\n<p>Adem\u00e1s, se trabaja en la realizaci\u00f3n de tr\u00edpticos que contengan un directorio para que los migrantes sepan a donde acudir para resguardarse, as\u00ed como recibir alimento y asistencia m\u00e9dica.<\/p>\n\n\n\n<p>En otros temas, Urrutia de la Torre inform\u00f3 que la UMDH en conjunto con el Instituto Federal de Defensor\u00eda P\u00fablica de Coahuila (IFDP), organizaron una jornada de atenci\u00f3n durante una semana, para proporcionar asesor\u00edas legales, en las instalaciones de la Presidencia Municipal, misma que tuvo una buena respuesta de la poblaci\u00f3n por lo que se contempla su realizaci\u00f3n de manera trimestral.<\/p>\n\n\n\n<p>El funcionario inform\u00f3 finalmente que en la Unidad se atendi\u00f3 en los primeros meses del a\u00f1o a 74 personas, adem\u00e1s se realizaron 16 gestorias,1 canalizaci\u00f3n, 8 atenciones especiales y 19 visitas para asesor\u00eda en documentaci\u00f3n.<\/p>\n\n\n\n<p>Refiri\u00f3 que en algunos casos la ciudadan\u00eda abandona el procedimiento por lo que luego de 45 d\u00edas, si no se tiene respuesta a las m\u00faltiples llamadas telef\u00f3nicas o notificaciones, se da por concluida la queja, por lo que exhort\u00f3 a las personas tomarse el tiempo para darle continuidad y se resuelva su inquietud.<\/p>\n\n\n\n<p>Asimismo, como parte de la atenci\u00f3n que se brinda durante las 24 horas, dijo que se registraron tres intervenciones en casos urgentes, as\u00ed como la presencia en el operativo alcohol\u00edmetro.<\/p>\n\n\n\n<p>Lo anterior fue dado a conocer en la d\u00e9cima quinta sesi\u00f3n de la Comisi\u00f3n de Derechos Humanos e Igualdad de G\u00e9nero, misma que preside la regidora Blanca \u00c1lvarez Garza y la integran los ediles Zazil Pacheco P\u00e9rez, Jos\u00e9 Manuel Riveroll Duarte, Christian Gonz\u00e1lez Zambrano, Karla Liliana Centeno F\u00e9lix, Alma Lucina Fong Mel\u00e9ndez y M\u00f3nica Montero Cuellar<\/p>\n\n\n\n<p><em>&#8211;&nbsp; Torre\u00f3n \u00a1Siempre Puede! &#8211;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 14 de marzo de 2023. La Unidad Municipal de Derechos Humanos (UMDH) de Torre\u00f3n en coordinaci\u00f3n con otras dependencias y asociaciones civiles, desarrolla acciones permanentes en atenci\u00f3n a los migrantes que est\u00e1n de paso por la ciudad, as\u00ed lo inform\u00f3 Miguel \u00c1ngel Urrutia de la Torre, titular de la dependencia a ediles [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14200,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14198"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=14198"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14198\/revisions"}],"predecessor-version":[{"id":14201,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/14198\/revisions\/14201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/14200"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=14198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=14198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=14198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}