{"id":16013,"date":"2023-04-19T19:03:20","date_gmt":"2023-04-19T19:03:20","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=16013"},"modified":"2023-04-19T19:04:26","modified_gmt":"2023-04-19T19:04:26","slug":"cfe-incumple-principio-de-acuerdo-con-gobierno-municipal-de-lerdo","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/04\/19\/cfe-incumple-principio-de-acuerdo-con-gobierno-municipal-de-lerdo\/","title":{"rendered":"<em>CFE INCUMPLE PRINCIPIO DE ACUERDO CON GOBIERNO MUNICIPAL DE LERDO<\/em>"},"content":{"rendered":"\n<p>Lerdo, 19 de abril 2023.- Aldo Rubio Mart\u00ednez, Jur\u00eddico Municipal de ciudad Lerdo, se refiri\u00f3 este mi\u00e9rcoles al corte de energ\u00eda de los edificios municipales, Presidencia, oficinas del SAPAL y DIF, as\u00ed como los pozos de agua potable de la ciudad, por parte de Comisi\u00f3n Federal de Electricidad, catalogando como un incumplimiento al principio con el Gobierno de Lerdo.<\/p>\n\n\n\n<p>\u201cEstamos confundidos y extra\u00f1ados, ya que, como de manera previa fue informado, hicimos visitas a la ciudad de M\u00e9xico, para llegar a un convenio de peso por peso para que nosotros pudi\u00e9ramos dirimir, seguir trabajando y reforzar los lazos que se tienen con esta dependencia federal, el d\u00eda de hoy nos tom\u00f3 por sorpresa que se incumple este principio de acuerdo\u201d se\u00f1al\u00f3.<\/p>\n\n\n\n<p>El funcionario comparti\u00f3 que la Comisi\u00f3n Federal de Electricidad tiene un adeudo con el municipio de 266 millones 302 mil 480 pesos, con un concepto de Predial, Uso de Suelo, dictamen de Protecci\u00f3n Civil y Factibilidad, que antecede del a\u00f1o 2017 a la fecha. Por ello se lleg\u00f3 a la finalidad de clausurar las tres dependencias de CFE ubicadas en el Municipio; Av. Agust\u00edn Castro, Ju\u00e1rez e Hidalgo y la Termoel\u00e9ctrica de Villa Ju\u00e1rez.<\/p>\n\n\n\n<p>Por su parte, el Ayuntamiento de Lerdo presenta una deuda de 193 millones 441 mil pesos, mismo que ser\u00eda resuelto a trav\u00e9s de un convenio de peso por peso. \u201cNosotros mandamos una nota informativa, a la Secretar\u00eda de Gobernaci\u00f3n, puesto que ellos, como \u00f3rgano garante, han sido quienes nos han dado apertura para estas negociaciones encabezadas por el Alcalde Homero Mart\u00ednez Cabrera\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>\u201cHay deuda por parte de CFE y han afectado a la ciudadan\u00eda en general con el corte de energ\u00eda en los pozos de agua, est\u00e1n atentando en contra de los derechos humanos de nuestro Municipio, al vernos agraviados, estamos siendo perjudicados, pedimos a la ciudadan\u00eda que tenga calma, pues estamos trabajando en beneficio de la gente, y buscaremos las soluciones correspondientes\u201d concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lerdo, 19 de abril 2023.- Aldo Rubio Mart\u00ednez, Jur\u00eddico Municipal de ciudad Lerdo, se refiri\u00f3 este mi\u00e9rcoles al corte de energ\u00eda de los edificios municipales, Presidencia, oficinas del SAPAL y DIF, as\u00ed como los pozos de agua potable de la ciudad, por parte de Comisi\u00f3n Federal de Electricidad, catalogando como un incumplimiento al principio con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16014,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16013"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=16013"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16013\/revisions"}],"predecessor-version":[{"id":16015,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16013\/revisions\/16015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/16014"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=16013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=16013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=16013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}