{"id":16017,"date":"2023-04-19T19:05:35","date_gmt":"2023-04-19T19:05:35","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=16017"},"modified":"2023-04-19T19:05:48","modified_gmt":"2023-04-19T19:05:48","slug":"sapal-atiende-el-100-de-los-reportes-de-fugas-en-24-horas-2","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/04\/19\/sapal-atiende-el-100-de-los-reportes-de-fugas-en-24-horas-2\/","title":{"rendered":"<em>SAPAL ATIENDE EL 100% DE LOS REPORTES DE FUGAS EN 24 HORAS<\/em>"},"content":{"rendered":"\n<p>Lerdo, 18 de abril 2023.- El director operativo del Sistema de Agua Potable y Alcantarillado en Lerdo (SAPAL), Alfredo Molina, inform\u00f3 que el personal a su cargo atiende el cien por ciento de los reportes de fugas en un lapso de 24 horas, por lo que asegur\u00f3 que los ciudadanos pueden tener certeza de la eficiencia del servicio.<\/p>\n\n\n\n<p>El funcionario invit\u00f3 a la ciudadan\u00eda a reportar cualquier incidente relacionado con el servicio de agua potable, todas las llamadas que reciban a trav\u00e9s del n\u00famero telef\u00f3nico 87 17 25 52 26 son atendidas.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que se cuenta con cuatro cuadrillas especiales para trabajar en materia de atenci\u00f3n a fugas, \u201cEstamos preparados para solucionar cualquier problema relacionado con fugas de agua potable, asegurando que los ciudadanos de Lerdo tengan acceso a agua limpia y potable en todo momento, es una instrucci\u00f3n del Alcalde Homero Mart\u00ednez y del gerente general Ignacio Ram\u00edrez\u201d.<\/p>\n\n\n\n<p>Es importante destacar que el sistema operador del SAPAL y el Gobierno Municipal realizan esfuerzos coordinados para dotar de agua potable a los ciudadanos, a trav\u00e9s de los trabajos de mantenimiento y rehabilitaci\u00f3n de pozos de agua, y de esta manera, garantizar el abastecimiento del vital l\u00edquido durante la temporada m\u00e1s fuerte de calor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lerdo, 18 de abril 2023.- El director operativo del Sistema de Agua Potable y Alcantarillado en Lerdo (SAPAL), Alfredo Molina, inform\u00f3 que el personal a su cargo atiende el cien por ciento de los reportes de fugas en un lapso de 24 horas, por lo que asegur\u00f3 que los ciudadanos pueden tener certeza de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16017"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=16017"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16017\/revisions"}],"predecessor-version":[{"id":16019,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/16017\/revisions\/16019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/16018"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=16017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=16017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=16017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}