{"id":17451,"date":"2023-05-16T02:32:02","date_gmt":"2023-05-16T02:32:02","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=17451"},"modified":"2023-05-16T02:32:50","modified_gmt":"2023-05-16T02:32:50","slug":"el-magisterio-ha-sido-solidario-con-mi-gobierno-mars","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/05\/16\/el-magisterio-ha-sido-solidario-con-mi-gobierno-mars\/","title":{"rendered":"<strong>\u2018EL MAGISTERIO HA SIDO SOLIDARIO CON MI GOBIERNO\u2019: MARS<\/strong>"},"content":{"rendered":"\n<ul>\n<li><strong><em>&nbsp;Junto a directivos de la Secci\u00f3n 35 del SNTE, el gobernador Miguel Riquelme reconoce la labor de las maestras y los maestros de Coahuila.<\/em><\/strong><\/li>\n\n\n\n<li><strong><em>&nbsp;Entregan la Presea Magisterial a docentes con 30, 40 y 50 a\u00f1os de servicio.<\/em><\/strong><\/li>\n<\/ul>\n\n\n\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 15 de Mayo de 2023.- En el marco de la celebraci\u00f3n del D\u00eda del Maestro, el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds acompa\u00f1\u00f3 a los integrantes de la Secci\u00f3n 35 del Sindicato Nacional de Trabajadores (SNTE) en la ceremonia donde se entregaron preseas a maestras y maestros por 30, 40 y 50 a\u00f1os de servicio.<\/p>\n\n\n\n<p>Al acompa\u00f1ar a Arturo D\u00edaz Gonz\u00e1lez, Secretario General de la Secci\u00f3n 35 del SNTE, y a Lorenzo Salazar Lozano, representante del Comit\u00e9 Ejecutivo Nacional de la Secci\u00f3n 35 del SNTE, el Mandatario estatal felicit\u00f3 a las y los galardonados y, desde luego, a todas y todos los docentes a lo largo y ancho de la entidad, en su d\u00eda.<\/p>\n\n\n\n<p>\u201cUstedes son protagonistas de los cap\u00edtulos hist\u00f3ricos de nuestro estado\u201d, dijo, al recordar cuando Torre\u00f3n estuvo en las listas de los lugares m\u00e1s peligrosos del mundo, y que gracias a la comunidad magisterial y al esfuerzo de los tres \u00f3rdenes de Gobierno se logr\u00f3 que dejara atr\u00e1s esa etapa.<\/p>\n\n\n\n<p>\u201cGracias a su valent\u00eda, hoy Coahuila tiene mejores par\u00e1metros\u201d, expuso.<\/p>\n\n\n\n<p>Riquelme Sol\u00eds reiter\u00f3 que hasta el \u00faltimo d\u00eda de su Gobierno trabajar\u00e1 por la seguridad, con el apoyo del Ej\u00e9rcito Mexicano: \u201cQue siempre nos ha ayudado a salvaguardar la vida de las y los coahuilenses\u201d.<\/p>\n\n\n\n<p>De la misma manera, hizo un reconocimiento p\u00fablico a los homenajeados y al magisterio en general, al enfatizar que han sido pieza fundamental para la recuperaci\u00f3n de empleo, pues las grandes empresas escogieron Coahuila por su nivel educativo.<\/p>\n\n\n\n<p>\u201cHemos sido un Gobierno solidario con el sector educativo; a cinco a\u00f1os de mi Gobierno, nunca pusimos en duda las prerrogativas ni los salarios de las y los maestros\u201d, coment\u00f3.<\/p>\n\n\n\n<p>Miguel Riquelme refrend\u00f3 su compromiso por mejorar sus condiciones laborales, porque tengan la infraestructura necesaria para realizar de manera \u00f3ptima su compromiso con la educaci\u00f3n.<\/p>\n\n\n\n<p>Por su parte, Arturo D\u00edaz Gonz\u00e1lez, Secretario General de la Secci\u00f3n 35 del SNTE, a nombre de los integrantes de este sindicato, agradeci\u00f3 el apoyo incondicional del gobernador Miguel Riquelme para esta agrupaci\u00f3n, pues siempre han buscado juntos el darles salida a las problem\u00e1ticas del sector.<\/p>\n\n\n\n<p>Recalc\u00f3 que es un d\u00eda inolvidable para los homenajeados, pues ni las distancias ni la falta de transporte ni los lugares alejados, han sido impedimento para las y los maestros, pues con su profesi\u00f3n han dejado huella en cientos o miles de j\u00f3venes.<\/p>\n\n\n\n<p>\u201cMis felicitaciones a todas y todos, son orgullo del magisterio y de la Secci\u00f3n 35; la mejor inversi\u00f3n es la educaci\u00f3n, pues es transformar. Gracias por compartir la educaci\u00f3n y seguir transformando el Pa\u00eds\u201d, expres\u00f3.<\/p>\n\n\n\n<p>En su mensaje, Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, Alcalde de Torre\u00f3n, mencion\u00f3 que m\u00e1s de 11 mil maestras y maestros dedican su esfuerzo y compromiso para educar a 190 mil j\u00f3venes de Torre\u00f3n, y expres\u00f3 su mayor reconocimiento al magisterio por formar a la ni\u00f1ez y juventud de esta ciudad.<\/p>\n\n\n\n<p>Al evento, que se desarroll\u00f3 en el Centro de Convenciones de Torre\u00f3n, acudieron, adem\u00e1s, Ver\u00f3nica Mart\u00ednez Garc\u00eda, senadora de la Rep\u00fablica; Eduardo Olmos Castro, diputado Presidente de la Junta de Gobierno del Congreso del Estado, y Francisco Saracho Navarro, Secretario de Educaci\u00f3n de Coahuila.<\/p>\n\n\n\n<p>Tambi\u00e9n Mario Cepeda Ram\u00edrez, diputado local, y Jorge Alberto Salcido Portillo, Subsecretario de Educaci\u00f3n B\u00e1sica del Estado.<\/p>\n\n\n\n<p>\u2014000\u2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila de Zaragoza; a 15 de Mayo de 2023.- En el marco de la celebraci\u00f3n del D\u00eda del Maestro, el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds acompa\u00f1\u00f3 a los integrantes de la Secci\u00f3n 35 del Sindicato Nacional de Trabajadores (SNTE) en la ceremonia donde se entregaron preseas a maestras y maestros por 30, 40 y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17451"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=17451"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17451\/revisions"}],"predecessor-version":[{"id":17453,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17451\/revisions\/17453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/17452"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=17451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=17451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=17451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}