{"id":17734,"date":"2023-05-20T03:23:27","date_gmt":"2023-05-20T03:23:27","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=17734"},"modified":"2023-05-20T03:23:31","modified_gmt":"2023-05-20T03:23:31","slug":"sesionan-en-favor-de-la-protecion-a-la-mujer-en-lerdo","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/05\/20\/sesionan-en-favor-de-la-protecion-a-la-mujer-en-lerdo\/","title":{"rendered":"<em>SESIONAN EN FAVOR DE LA PROTECI\u00d3N A LA MUJER EN LERDO<\/em>"},"content":{"rendered":"\n<p>Lerdo, 19 de mayo 2023.- El jueves pasado se llev\u00f3 a cabo la primera sesi\u00f3n del consejo del Instituto Municipal de la Mujer, en el Sal\u00f3n de Usos M\u00faltiples \u2018Carmen Carre\u00f3n\u2019 de la Unidad Administrativa de San Isidro, con el objetivo de trabajar en favor de las lerdenses mediante acciones para combatir la violencia.<\/p>\n\n\n\n<p>En la reuni\u00f3n se cont\u00f3 con la participaci\u00f3n del Secretario del Ayuntamiento Jes\u00fas Eduardo Lara Urby, en representaci\u00f3n del Presidente Municipal Homero Mart\u00ednez Cabrera; la titular del Instituto de la Mujer, Mar\u00eda del Refugio Adame G\u00fcereca; la agente del Ministerio P\u00fablico de la Unidad de Investigaci\u00f3n Especializada en Delitos Contra la Familia y Delitos Sexuales, Lourdes Yadira Padilla Rodr\u00edguez; la representante legal de la organizaci\u00f3n YHVH JHANUN VERA JHUM. A.C., Luc\u00eda Barbalena Espinoza.<\/p>\n\n\n\n<p>As\u00ed como el subdirector de Seguridad P\u00fablica Jos\u00e9 Luis Olivares Guzm\u00e1n, representando al director H\u00e9ctor Adolfo Mart\u00ednez L\u00f3pez; el titular de Desarrollo Social, Daniel Salazar Gallegos; la cuarta regidora Mar\u00eda Luisa Gonz\u00e1lez L\u00f3pez, quien funge como presidenta de la comisi\u00f3n de la mujer Equidad y G\u00e9nero; y la sexta regidora y vocal de la comisi\u00f3n, Ana Mar\u00eda Dur\u00f3n P\u00e9rez.<\/p>\n\n\n\n<p>Uno de los principales temas que se abordaron durante la comisi\u00f3n, fue la implementaci\u00f3n de estrategias y el reforzamiento de acciones para prevenir y erradicar la violencia contra las mujeres, pues Lerdo se mantiene a la baja en materia de violencia de g\u00e9nero.<\/p>\n\n\n\n<p>Se puntualizaron las labores que el instituto realiza en beneficio a la protecci\u00f3n de la mujer, desde la promoci\u00f3n y difusi\u00f3n de los servicios, la publicaci\u00f3n de audiovisuales y c\u00e1psulas informativas en redes sociales, hasta el trabajo en campo con los m\u00f3dulos de atenci\u00f3n, visitas domiciliarias, talleres de empoderamiento, pl\u00e1ticas y conferencias en escuelas e instituciones p\u00fablicas, brigadas en colaboraci\u00f3n con SEDENA y Guardia Nacional, la difusi\u00f3n del violent\u00f3metro y el programa \u2018Por ti, por m\u00ed, \u00a1por todas!, este \u00faltimo realizado en coordinaci\u00f3n con la DSPM.<\/p>\n\n\n\n<p>La directora de la dependencia municipal, Refugio Adame, puntualiz\u00f3 que los \u00edndices de violencia han disminuido gracias al apoyo y trabajo coordinado con Visefiscal\u00eda, SEDENA, Guardia Nacional y Seguridad P\u00fablica, as\u00ed como el trabajo para reforzar las actividades de prevenci\u00f3n, atenci\u00f3n, sanci\u00f3n, y erradicaci\u00f3n de la violencia hacia la mujer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lerdo, 19 de mayo 2023.- El jueves pasado se llev\u00f3 a cabo la primera sesi\u00f3n del consejo del Instituto Municipal de la Mujer, en el Sal\u00f3n de Usos M\u00faltiples \u2018Carmen Carre\u00f3n\u2019 de la Unidad Administrativa de San Isidro, con el objetivo de trabajar en favor de las lerdenses mediante acciones para combatir la violencia. En [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17735,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17734"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=17734"}],"version-history":[{"count":2,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17734\/revisions"}],"predecessor-version":[{"id":17738,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17734\/revisions\/17738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/17735"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=17734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=17734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=17734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}