{"id":17788,"date":"2023-05-21T22:51:32","date_gmt":"2023-05-21T22:51:32","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=17788"},"modified":"2023-05-21T22:51:35","modified_gmt":"2023-05-21T22:51:35","slug":"durango-recibira-apoyos-para-proyectos-culturales-y-artisticos-anuncia-secretaria-de-cultura","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/05\/21\/durango-recibira-apoyos-para-proyectos-culturales-y-artisticos-anuncia-secretaria-de-cultura\/","title":{"rendered":"<em>Durango recibir\u00e1 apoyos para proyectos culturales y art\u00edsticos, anuncia secretaria de Cultura.<\/em>"},"content":{"rendered":"\n<p><em>\u2022 Alejandra Frausto inform\u00f3 que junto al Gobierno de Esteban, se abrir\u00e1 la convocatoria del Programa de Est\u00edmulo a la Creaci\u00f3n y Desarrollo Art\u00edstico (PECDA).<\/em><\/p>\n\n\n\n<p><em>\u2022 Reconoci\u00f3 en Villegas Villarreal su sensibilidad, y quien al ser artista, entiende perfectamente lo que es el arte y la cultura.<\/em><\/p>\n\n\n\n<p>\u201cEsteban Villegas es un gobernador sensible, un artista que entiende perfectamente algo que durante mucho tiempo se crey\u00f3 que era un privilegio de unos cuantos, que es el derecho a la cultura\u201d, expres\u00f3 la titular de la Secretar\u00eda de Cultura de M\u00e9xico, Alejandra Frausto Guerrero al anunciar la apertura de convocatorias para apoyar proyectos art\u00edsticos y culturales.<\/p>\n\n\n\n<p>Para seguir potenciando la creatividad de los duranguenses, Alejandra Frausto destac\u00f3 que pr\u00f3ximamente se abrir\u00e1 la convocatoria del Programa de Est\u00edmulo a la Creaci\u00f3n y Desarrollo Art\u00edstico (PECDA), la cual facilitar\u00e1 el desarrollo de proyectos culturales y art\u00edsticos en el estado, a trav\u00e9s de la oferta de recursos que permitan su realizaci\u00f3n, ejecuci\u00f3n y logren nuevas formas de comunicar, formular, expresar, visibilizar y enunciar desde el \u00e1mbito art\u00edstico.<\/p>\n\n\n\n<p>Durango es tierra de creadores, coment\u00f3 al destacar que adem\u00e1s tiene una diversidad cultural extraordinaria; la ciudad es excepcional y todas sus regiones muestran una riqueza cultural \u00fanica.<\/p>\n\n\n\n<p>\u201cEstamos muy felices de estar aqu\u00ed, vamos a seguir trabajando y construyendo de la mano\u201d, abund\u00f3.<\/p>\n\n\n\n<p>Por su parte, el director del Instituto de Cultura del Estado (ICED), Francisco P\u00e9rez Meza, se\u00f1al\u00f3 que con el respaldo del Presidente de la Rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, as\u00ed como de la secretaria Alejandra Frausto, vienen grandes noticias para los creadores, colectivos y grupos organizados de los municipios, regiones, pueblos y comunidades en esta materia; \u201cestoy seguro que habremos de seguir trabajando de la mano con el Gobierno Federal, para que Durango destaque con su talento en todo el pa\u00eds \u201d, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Alejandra Frausto inform\u00f3 que junto al Gobierno de Esteban, se abrir\u00e1 la convocatoria del Programa de Est\u00edmulo a la Creaci\u00f3n y Desarrollo Art\u00edstico (PECDA). \u2022 Reconoci\u00f3 en Villegas Villarreal su sensibilidad, y quien al ser artista, entiende perfectamente lo que es el arte y la cultura. \u201cEsteban Villegas es un gobernador sensible, un artista [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17788"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=17788"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17788\/revisions"}],"predecessor-version":[{"id":17790,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17788\/revisions\/17790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/17789"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=17788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=17788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=17788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}