{"id":19274,"date":"2023-06-10T22:16:29","date_gmt":"2023-06-10T22:16:29","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=19274"},"modified":"2023-06-10T22:16:34","modified_gmt":"2023-06-10T22:16:34","slug":"el-impresionante-triunfo-de-mexicanas","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/06\/10\/el-impresionante-triunfo-de-mexicanas\/","title":{"rendered":"EL IMPRESIONANTE TRIUNFO DE MEXICANAS"},"content":{"rendered":"\n<p>Rutina del equipo de M\u00e9xico por el oro con puntaje m\u00e1ximo de 227.6626 en la rutina Acrob\u00e1tica en el Mundial de Nataci\u00f3n Art\u00edstica<\/p>\n\n\n\n<p><a href=\"https:\/\/m.facebook.com\/story.php?story_fbid=pfbid0v9x2BfijyoUbAHKbQdCNSinZWvNS8uvxBsfMJXPCW1zAUM7ozqrWMjNDsF2NyaCsl&amp;id=624517634317090&amp;mibextid=Nif5oz\">https:\/\/m.facebook.com\/story.php?story_fbid=pfbid0v9x2BfijyoUbAHKbQdCNSinZWvNS8uvxBsfMJXPCW1zAUM7ozqrWMjNDsF2NyaCsl&amp;id=624517634317090&amp;mibextid=Nif5oz<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rutina del equipo de M\u00e9xico por el oro con puntaje m\u00e1ximo de 227.6626 en la rutina Acrob\u00e1tica en el Mundial de Nataci\u00f3n Art\u00edstica https:\/\/m.facebook.com\/story.php?story_fbid=pfbid0v9x2BfijyoUbAHKbQdCNSinZWvNS8uvxBsfMJXPCW1zAUM7ozqrWMjNDsF2NyaCsl&amp;id=624517634317090&amp;mibextid=Nif5oz<\/p>\n","protected":false},"author":1,"featured_media":19275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19274"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19274"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19274\/revisions"}],"predecessor-version":[{"id":19276,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19274\/revisions\/19276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/19275"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}