{"id":23490,"date":"2023-08-11T23:20:24","date_gmt":"2023-08-11T23:20:24","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=23490"},"modified":"2023-08-11T23:20:30","modified_gmt":"2023-08-11T23:20:30","slug":"la-libertad-de-catedra","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/08\/11\/la-libertad-de-catedra\/","title":{"rendered":"LA LIBERTAD DE C\u00c1TEDRA"},"content":{"rendered":"\n<p>Por Fernando Rangel de Le\u00f3n<\/p>\n\n\n\n<p>Los padres de familia no deben de estar preocupados por los Libros de Texto Gratuitos, porque \u00e9stos no impiden que los profesores&nbsp; les ense\u00f1en a sus hijos conocimientos que no vienen en ellos o se los corrijan; pues estos libros son la base y la gu\u00eda de los planes de estudio y de los programas de ense\u00f1anza, de los que no deben de apartarse, sino desarrollarlos.<\/p>\n\n\n\n<p>La libertad de c\u00e1tedra es el derecho de los profesores de investigar, ense\u00f1ar y divulgar el conocimiento de las ideas y&nbsp; de las convicciones, de acuerdo con su capacidad y conforme a su experiencia, sin m\u00e1s l\u00edmites que la propia materia de su asignatura; sin presiones laborales, sindicales, econ\u00f3micas, pol\u00edticas o de cualquier otra \u00edndole; garantizada como un derecho humano en el 3\u00b0 Constitucional.<\/p>\n\n\n\n<p>De manera que si en los nuevos libros de texto gratuitos, que ser\u00e1n entregados el pr\u00f3ximo lunes 28 de agosto, vienen algunas peccata minuta (peque\u00f1as faltas), seguramente los profesores las corregir\u00e1n y les har\u00e1n saber a los educandos la verdad; pues el entorno en el que se elaboraron&nbsp; es el de la 4T, que pretende una transformaci\u00f3n radical en la educaci\u00f3n para que pueda haberla en todo el sistema de la vida p\u00fablica.<\/p>\n\n\n\n<p>Respecto de los libros de texto gratuitos, transcribo parte de la declaraci\u00f3n de Manuel Gil Ant\u00f3n \u201cuno de los m\u00e1s inteligentes investigadores sobre los asuntos de educaci\u00f3n en el pa\u00eds\u2026\u201d, citado por Carlos Puig, en Duda Razonable, del pasado mi\u00e9rcoles 9 de agosto, en Milenio Diario La Opini\u00f3n Laguna: \u201cPara decirlo en s\u00edntesis, es la propuesta de que todos los ni\u00f1os, ni\u00f1as y adolescentes mexicanos asistan a una escuela activa en la cual no est\u00e9 fragmentado el conocimiento, sino que se aprenda a partir de proyectos, problemas que ellos viven, que se viven en el mundo y que a trav\u00e9s de ellos se incorporen los conocimientos que antes incorporaba fragmentariamente por materias\u201d.<\/p>\n\n\n\n<p>\u201cEse asunto, ese sobre el cual descansan los libros de texto, los programas, etc\u00e9tera. Si no entendemos que ese cambio, de esa magnitud, es que est\u00e1 en juego, nos quedamos por las ramas, como se dice, y no entendemos&nbsp; que creo que la discusi\u00f3n nacional tendr\u00eda que ser esa. Y, sobre todo, \u00bfa qu\u00e9 ritmo hacemos esa transformaci\u00f3n?\u201d<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Por lo que los padres de familia de todo el pa\u00eds no deben tener temor alguno por los nuevos libros de texto gratuitos; ya que lo que pasa es que desde 1959, en que los implant\u00f3 el gobierno de Adolfo L\u00f3pez Mateos, no hab\u00edan tenido una transformaci\u00f3n como lo est\u00e1n teniendo en esta 4T.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Fernando Rangel de Le\u00f3n Los padres de familia no deben de estar preocupados por los Libros de Texto Gratuitos, porque \u00e9stos no impiden que los profesores&nbsp; les ense\u00f1en a sus hijos conocimientos que no vienen en ellos o se los corrijan; pues estos libros son la base y la gu\u00eda de los planes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23491,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23490"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=23490"}],"version-history":[{"count":2,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23490\/revisions"}],"predecessor-version":[{"id":23494,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/23490\/revisions\/23494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/23491"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=23490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=23490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=23490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}