{"id":25461,"date":"2023-09-14T02:43:50","date_gmt":"2023-09-14T02:43:50","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=25461"},"modified":"2023-09-27T22:17:33","modified_gmt":"2023-09-27T22:17:33","slug":"clausuran-congeladores-de-carniceria-insalubre-de-la-colonia-provitec","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/09\/14\/clausuran-congeladores-de-carniceria-insalubre-de-la-colonia-provitec\/","title":{"rendered":"<strong>Clausuran congeladores de carnicer\u00eda insalubre de la colonia Provitec<\/strong>"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 14 de septiembre de 2023<\/p>\n\n\n\n<p>Una carnicer\u00eda insalubre, considerada un grave foco de infecci\u00f3n y de enfermedades, fue detectada por personal de la Direcci\u00f3n de Inspecci\u00f3n y Verificaci\u00f3n, en la calle Isaac Newton de la colonia Provitec, luego de ser denunciada por obstruir el drenaje sanitario al verter agua sucia, sangre y v\u00edsceras por las alcantarillas.<\/p>\n\n\n\n<p>El titular de la dependencia municipal, Ra\u00fal Gerardo Rodr\u00edguez Garc\u00eda, inform\u00f3 que se procedi\u00f3 con la colocaci\u00f3n de sellos a los congeladores de esta supuesta carnicer\u00eda, en virtud de que no se puede clausurar por ser parte de la casa habitaci\u00f3n de los propietarios.<\/p>\n\n\n\n<p>Adem\u00e1s de comprobar la falta de licencia de funcionamiento, de certificado de fumigaci\u00f3n y de tarjetas de salud, se constat\u00f3 que en el piso, las paredes y en el equipo usado para almacenar le carne prevalec\u00eda la suciedad.<\/p>\n\n\n\n<p>Uno de los vecinos afectados dijo que dicha situaci\u00f3n no es reciente y que frecuentemente se derraman aguas por las coladeras, adem\u00e1s de que en esta temporada de calor los malos olores penetran al interior de los domicilios.<\/p>\n\n\n\n<p>Los residentes en el \u00e1rea exhortaron a las autoridades municipales a verificar la actividad que ah\u00ed se realizaba, debido a la serie de molestias que se ven\u00edan causando a todos los colonos.<\/p>\n\n\n\n<p>\u201cEsto ya tiene tiempo y generalmente es por las tardes cuando tiran desechos, agua apestosa que se queda en la calle, porque se colapsa el drenaje, pero lo peor es que todo es a unos cuantos metros de las casas\u201d, dijo un denunciante.<\/p>\n\n\n\n<p>Los vecinos mencionan que es un foco de infecci\u00f3n que afecta la salud de las personas, aparte de que el olor se impregna en las prendas de vestir y es desagradable.<\/p>\n\n\n\n<p>Al respecto, el funcionario propuso la revisi\u00f3n del drenaje al Sistema Municipal de Aguas y Saneamiento (SIMAS), por lo que en el transcurso de hoy y ma\u00f1ana estar\u00e1 siendo destapado y se verificar\u00e1 que no exista alguna otra irregularidad.<\/p>\n\n\n\n<p><em>&#8211;&nbsp; Torre\u00f3n \u00a1Siempre Puede! &#8211;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 14 de septiembre de 2023 Una carnicer\u00eda insalubre, considerada un grave foco de infecci\u00f3n y de enfermedades, fue detectada por personal de la Direcci\u00f3n de Inspecci\u00f3n y Verificaci\u00f3n, en la calle Isaac Newton de la colonia Provitec, luego de ser denunciada por obstruir el drenaje sanitario al verter agua sucia, sangre y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25461"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=25461"}],"version-history":[{"count":2,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25461\/revisions"}],"predecessor-version":[{"id":26407,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25461\/revisions\/26407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/25462"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=25461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=25461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=25461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}