{"id":25580,"date":"2023-09-13T03:31:39","date_gmt":"2023-09-13T03:31:39","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=25580"},"modified":"2023-09-13T03:31:42","modified_gmt":"2023-09-13T03:31:42","slug":"inauguran-vivero-educativo-en-el-centro-de-educacion-ambiental-y-vigilancia-climatica-de-la-uadec","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2023\/09\/13\/inauguran-vivero-educativo-en-el-centro-de-educacion-ambiental-y-vigilancia-climatica-de-la-uadec\/","title":{"rendered":"<strong>Inauguran Vivero Educativo en el Centro de Educaci\u00f3n Ambiental y Vigilancia Clim\u00e1tica de la UAdeC<\/strong>"},"content":{"rendered":"\n<p>ARTEAGA, Coahuila. 11 de septiembre de 2023. El rector de la Universidad Aut\u00f3noma de Coahuila, Salvador Hern\u00e1ndez V\u00e9lez, encabez\u00f3 la ceremonia de inauguraci\u00f3n del Vivero Educativo del Centro de Educaci\u00f3n Ambiental y Vigilancia Clim\u00e1tica ubicado en Ciudad Universitaria de Arteaga.<\/p>\n\n\n\n<p>Asistieron al evento inaugural la coordinadora de Agenda Ambiental Universitaria, Graciela Hern\u00e1ndez G\u00f3mez; el coordinador de Unidad Saltillo, Julio Saucedo Zul; el gerente de Recursos Humanos de la empresa <em>Daimler Truck <\/em>Norte Am\u00e9rica (DTNA), Israel Salazar; el presidente del Club de Sustentabilidad de DTNA, Carlos Castillo.<\/p>\n\n\n\n<p>As\u00ed como la directora de Conservaci\u00f3n San Lorenzo A.C., Carolina Monroy; el coordinador operativo de la Reserva Estatal Sierra de Zapalinam\u00e9, Juan Manuel C\u00e1rdenas Villanueva, funcionariado de la UAdeC, directivos y comunidad docente y estudiantil de las Escuelas y Facultades del Campus Arteaga.<\/p>\n\n\n\n<p>En su mensaje de bienvenida, la titular de la Agenda Ambiental Universitaria, Graciela Hern\u00e1ndez G\u00f3mez, dijo que este espacio que se inaugura ser\u00e1 un Vivero de plantas nativas de la regi\u00f3n en el que se desarrollar\u00e1n proyectos para restauraci\u00f3n de \u00e1reas y conservaci\u00f3n de la flora del semi desierto, se proteger\u00e1n especies amenazadas en peligro de extinci\u00f3n y se reproducir\u00e1n plantas \u00fatiles de importancia ecol\u00f3gica para reforestar el Campus Universitario.<\/p>\n\n\n\n<p>Agradeci\u00f3 a la empresa DAIMLER por la donaci\u00f3n del vivero y por todo el apoyo brindado a trav\u00e9s de diferentes actividades en conjunto, hizo lo propio con PROFAUNA quien capacit\u00f3 al personal en cuestiones de conservaci\u00f3n de flora y fauna de la regi\u00f3n y a Conservaci\u00f3n San Lorenzo A.C. por ser el intermediario del donativo en especie.<\/p>\n\n\n\n<p>Por su parte, el rector, Salvador Hern\u00e1ndez V\u00e9lez destac\u00f3 la relevancia de este proyecto ya que el estado de Coahuila esta ubicado en el coraz\u00f3n del desierto chihuahuense, por lo que es importante cambiar la percepci\u00f3n sobre el entorno en el que vivimos y su biodiversidad, como un compromiso para preservar la naturaleza nativa de nuestro estado.<\/p>\n\n\n\n<p>En su intervenci\u00f3n, el presidente del Club de Sustentabilidad de Daimler Truck Norte Am\u00e9rica, Carlos Castillo expres\u00f3 la importancia del compromiso social de la empresa y su satisfacci\u00f3n por continuar colaborando con la UAdeC; destac\u00f3 el enfoque en fomentar la conciencia ambiental tanto en las generaciones actuales como en las futuras, resaltando la educaci\u00f3n ambiental como uno de los pilares fundamentales en su trabajo diario.<\/p>\n\n\n\n<p>Adem\u00e1s, destac\u00f3 la fuerte vinculaci\u00f3n que ha establecido con la Agenda Ambiental Universitaria, con proveedores, organismos y universidades para contribuir y unir esfuerzos para este tipo de actividades de sostenibilidad.<\/p>\n\n\n\n<p>Al finalizar la ceremonia de corte de list\u00f3n, las autoridades universitarias e invitados especiales, realizaron un recorrido por las instalaciones del Vivero, donde pudieron apreciar el equipamiento y las diferentes especies de plantas de la regi\u00f3n, as\u00ed como el equipo de riego con el que cuenta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ARTEAGA, Coahuila. 11 de septiembre de 2023. El rector de la Universidad Aut\u00f3noma de Coahuila, Salvador Hern\u00e1ndez V\u00e9lez, encabez\u00f3 la ceremonia de inauguraci\u00f3n del Vivero Educativo del Centro de Educaci\u00f3n Ambiental y Vigilancia Clim\u00e1tica ubicado en Ciudad Universitaria de Arteaga. Asistieron al evento inaugural la coordinadora de Agenda Ambiental Universitaria, Graciela Hern\u00e1ndez G\u00f3mez; el coordinador [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,56],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25580"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=25580"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25580\/revisions"}],"predecessor-version":[{"id":25582,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/25580\/revisions\/25582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/25581"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=25580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=25580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=25580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}