{"id":31683,"date":"2024-01-09T19:06:40","date_gmt":"2024-01-10T01:06:40","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=31683"},"modified":"2024-01-09T19:06:44","modified_gmt":"2024-01-10T01:06:44","slug":"a-la-bascula-manolo-no-esta-solo","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/01\/09\/a-la-bascula-manolo-no-esta-solo\/","title":{"rendered":"A LA B\u00c1SCULA MANOLO NO ESTA SOLO"},"content":{"rendered":"\n<p><strong><em>Juli\u00e1n Parra Ibarra<\/em><\/strong><\/p>\n\n\n\n<p>Sin decir agua va, de pronto el presidente nacional del PAN, Marko Cort\u00e9s, arremeti\u00f3 en contra del gobernador Manolo Jim\u00e9nez Salinas y el PRI coahuilense, poniendo evidentemente en riesgo la posibilidad de que en nuestra entidad se mantenga la alianza tambi\u00e9n integrada por el PRD, porque en la renovaci\u00f3n de \u00e9sta de cara a las elecciones de este a\u00f1o, no le quieren dar varias posiciones que reclama, entre ellas la candidatura a la alcald\u00eda de Torre\u00f3n.<\/p>\n\n\n\n<p>De inmediato corrieron versiones de qu\u00e9 es lo que est\u00e1 detr\u00e1s de esta \u2018valentonada\u2019, pero lo que s\u00ed es un hecho es que por donde se le vea, es un intento de chantaje, de someter y hacerle \u2018manita de puerco\u2019 a Jim\u00e9nez Salinas quien, es joven pero no tonto.<\/p>\n\n\n\n<p>Mucho m\u00e1s temprano que tarde, Manolo demostrar\u00e1 de qu\u00e9 est\u00e1 hecho, y as\u00ed fuera fuego amigo, mostrar\u00e1 su capacidad y el car\u00e1cter para afrontar esta y las situaciones que se le pongan en el camino. Pero adem\u00e1s en el tr\u00e1nsito de su administraci\u00f3n, el saltillense no va solo, el hecho de ser el gobernador que llega con la m\u00e1s alta cantidad de votos, m\u00e1s de 624 mil, le da la legitimidad y el apoyo pleno de los coahuilenses, que ya se lo externaron en las urnas.<\/p>\n\n\n\n<p>La posici\u00f3n que ha fijado el l\u00edder nacional panista es il\u00f3gica e irracional, de acuerdo con las aportaciones que su partido ha ofrecido en la alianza en las dos \u00fanicas entidades gobernadas por el PRI, Durango y Coahuila. La soberbia con la que ha irrumpido con este tema, le impide ver que Acci\u00f3n Nacional est\u00e1 convertido en un partido marginal, y no tiene las fichas suficientes como para ciertas negociaciones, y menos exigencias como las que pretende en Coahuila.<\/p>\n\n\n\n<p>Para tener un par\u00e1metro a manera prueba, ser\u00eda tanto como que el PRI le exigiera al PAN que las candidaturas a la gubernatura de estados como Guanajuato, Quer\u00e9taro o Aguascalientes, donde domina el blanquiazul, fueran para priistas. Usando el raciocinio, un escenario de esa naturaleza, ni se plantear\u00eda, y menos se conceder\u00eda.<\/p>\n\n\n\n<p>Es algo similar a lo que pretende Cort\u00e9s en Coahuila, mostrando un total desconocimiento del entorno de la entidad, y del municipio torreonense. Su caprichito le puede salir muy caro al PAN que, fuera de la alianza en nuestro estado podr\u00eda dirigirse al suicidio.<\/p>\n\n\n\n<p><a href=\"mailto:laotraplana@gmail.com\"><strong><em>laotraplana@gmail.com<\/em><\/strong><\/a><strong><em><\/em><\/strong><\/p>\n\n\n\n<p><strong><em>X= @JulianParraIba<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juli\u00e1n Parra Ibarra Sin decir agua va, de pronto el presidente nacional del PAN, Marko Cort\u00e9s, arremeti\u00f3 en contra del gobernador Manolo Jim\u00e9nez Salinas y el PRI coahuilense, poniendo evidentemente en riesgo la posibilidad de que en nuestra entidad se mantenga la alianza tambi\u00e9n integrada por el PRD, porque en la renovaci\u00f3n de \u00e9sta de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31683"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=31683"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31683\/revisions"}],"predecessor-version":[{"id":31685,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/31683\/revisions\/31685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/31684"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=31683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=31683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=31683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}