{"id":3228,"date":"2022-09-07T22:35:11","date_gmt":"2022-09-07T22:35:11","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=3228"},"modified":"2022-09-07T22:35:15","modified_gmt":"2022-09-07T22:35:15","slug":"pide-martha-loera-campanas-sobre-riesgos-de-no-atender-enfermedades-durante-el-embarazo","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2022\/09\/07\/pide-martha-loera-campanas-sobre-riesgos-de-no-atender-enfermedades-durante-el-embarazo\/","title":{"rendered":"Pide Martha Loera campa\u00f1as sobre riesgos de no atender enfermedades durante el embarazo"},"content":{"rendered":"\n<p>\u200b, Coahuila 07 septiembre 2022.- Durante la segunda sesi\u00f3n del Segundo Periodo Ordinario del segundo a\u00f1o de la Sexag\u00e9sima Segunda Legislatura del Congreso del Estado, se aprob\u00f3 por unanimidad un dictamen\u00a0de la Comisi\u00f3n de Salud, Medio Ambiente, Recursos Naturales y Agua,\u200b relativo a un punto de acuerdo presentado por\u00a0<strong>la diputada del PRI, Martha Loera Arambula<\/strong>,\u00a0con el objeto de exhortar a la Secretar\u00eda de Salud federal, para que promueva campa\u00f1as de concientizaci\u00f3n respecto de los riesgos de no atender durante la etapa gestante infecciones o enfermedades.<\/p>\n\n\n\n<p>Durante el embarazo, algunas infecciones comunes como el resfriado o una infecci\u00f3n en la piel, por lo regular no causan problemas graves. Sin embargo, algunas otras pueden transmitirse al feto, lesionarlo o provocar un aborto espont\u00e1neo, un parto prematuro, beb\u00e9s con bajo peso al nacer o incluso puede causar enfermedades graves, defectos cong\u00e9nitos y discapacidades de por vida, tales como la p\u00e9rdida de la audici\u00f3n o problemas de aprendizaje,\u00a0es por ello que resulta indispensable tomar las medidas necesarias para la prevenci\u00f3n y control de estas consecuencias.<\/p>\n\n\n\n<p>\u200b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u200b, Coahuila 07 septiembre 2022.- Durante la segunda sesi\u00f3n del Segundo Periodo Ordinario del segundo a\u00f1o de la Sexag\u00e9sima Segunda Legislatura del Congreso del Estado, se aprob\u00f3 por unanimidad un dictamen\u00a0de la Comisi\u00f3n de Salud, Medio Ambiente, Recursos Naturales y Agua,\u200b relativo a un punto de acuerdo presentado por\u00a0la diputada del PRI, Martha Loera Arambula,\u00a0con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3228"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3228"}],"version-history":[{"count":0,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3229"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}