{"id":35120,"date":"2024-04-09T20:40:02","date_gmt":"2024-04-10T02:40:02","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=35120"},"modified":"2024-04-09T20:40:04","modified_gmt":"2024-04-10T02:40:04","slug":"implementan-operativo-de-limpieza-en-espacios-publicos-con-motivo-del-eclipse","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/04\/09\/implementan-operativo-de-limpieza-en-espacios-publicos-con-motivo-del-eclipse\/","title":{"rendered":"Implementan operativo de limpieza en espacios p\u00fablicos con motivo del eclipse"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 09 de abril de 2024.<\/p>\n\n\n\n<p>Personal de La Ola realiz\u00f3 una jornada de limpieza, antes, durante y despu\u00e9s del eclipse total solar 2024, con el objetivo de mantener en condiciones adecuadas los principales espacios p\u00fablicos y lugares donde se reuni\u00f3 la ciudadan\u00eda, de los que se retiraron m\u00e1s de 23 toneladas de basura.<\/p>\n\n\n\n<p>Fernando Villarreal Cu\u00e9llar, titular de la Direcci\u00f3n General de Servicios P\u00fablicos, dijo que durante el desarrollo del evento astron\u00f3mico, fueron reforzados los lugares en los que se registrar\u00eda mayor afluencia, adem\u00e1s de las plazas p\u00fablicas que contaron con la presencia de familias.<\/p>\n\n\n\n<p>En el Bosque Urbano, acudi\u00f3 un equipo de 80 personas, donde recolectaron un total de 12 toneladas de residuos.<\/p>\n\n\n\n<p>Tambi\u00e9n en el emblem\u00e1tico Cristo de las Noas, 35 elementos se sumaron a la labor de limpieza, de donde retiraron cinco toneladas de desechos.<\/p>\n\n\n\n<p>Mencion\u00f3 que en los lugares ic\u00f3nicos como la Plaza Mayor, Alameda, Morelos y Plaza de Armas, 50 integrantes de La Ola recolectaron un total de seis toneladas de residuos.<\/p>\n\n\n\n<p>El funcionario dijo que adem\u00e1s de estos puntos, los trabajos se extendieron a un total de 56 plazas p\u00fablicas en las que se dispusieron tendederos de lentes para la observaci\u00f3n segura del eclipse. En cada uno de los lugares mencionados se reitiraron cinco kilos de residuos por punto aproximadamente.<\/p>\n\n\n\n<p>Mencion\u00f3 que la L\u00ednea Verde cont\u00f3 con el apoyo de 35 personas que no solo promovieron el uso adecuado de lentes, sino que tambi\u00e9n contribuyeron a la limpieza del \u00e1rea, en ese sitio se retir\u00f3 media tonelada de basura.<\/p>\n\n\n\n<p>Los trabajos de limpieza se realizaron durante el d\u00eda de ayer y parte de la ma\u00f1ana de este martes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 09 de abril de 2024. Personal de La Ola realiz\u00f3 una jornada de limpieza, antes, durante y despu\u00e9s del eclipse total solar 2024, con el objetivo de mantener en condiciones adecuadas los principales espacios p\u00fablicos y lugares donde se reuni\u00f3 la ciudadan\u00eda, de los que se retiraron m\u00e1s de 23 toneladas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35120"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=35120"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35120\/revisions"}],"predecessor-version":[{"id":35122,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35120\/revisions\/35122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/35121"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=35120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=35120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=35120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}