{"id":35263,"date":"2024-04-11T18:47:34","date_gmt":"2024-04-12T00:47:34","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=35263"},"modified":"2024-04-11T18:47:35","modified_gmt":"2024-04-12T00:47:35","slug":"ficha-tecnica-no-131-tema-atencion-a-medios-de-comunicacion","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/04\/11\/ficha-tecnica-no-131-tema-atencion-a-medios-de-comunicacion\/","title":{"rendered":"FICHA T\u00c9CNICA No. 131 TEMA: ATENCI\u00d3N A MEDIOS DE COMUNICACI\u00d3N"},"content":{"rendered":"\n<p>(INFORMATIVO)<\/p>\n\n\n\n<p>FECHA: 11\/04\/2024<\/p>\n\n\n\n<p>Este jueves, el Alcalde de Lerdo, Homero Mart\u00ednez Cabrera inform\u00f3 que, actualmente, el Sistema de Agua Potable y Alcantarillado de Lerdo (SAPAL) recibe un caudal de 450 litros por segundo, proveniente del Proyecto de Agua Saludable para la Laguna (ASL).<\/p>\n\n\n\n<p>\u201cHemos colaborado activamente con el mencionado proyecto, siendo el municipio piloto. Hemos estado supervisando y regulando el funcionamiento de los pozos, lo que, si bien implica ciertas contrapartes, es una medida necesaria para garantizar un suministro estable. Continuaremos trabajando en esta l\u00ednea\u00bb.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que en los \u00faltimos d\u00edas, el suministro de agua ha sido constante, sin variaciones significativas, lo que ha permitido desactivar ocho pozos de agua en la zona de San Fernando.<\/p>\n\n\n\n<p>En relaci\u00f3n con las obras adicionales del proyecto, mencion\u00f3 que recientemente visit\u00f3 la Villa de Le\u00f3n Guzm\u00e1n y la colonia Juan Jos\u00e9 Rojas, en donde se ha llevado a cabo la interconexi\u00f3n de agua al proyecto ASL y destac\u00f3 que el cambio de la red de agua potable en ambos sectores est\u00e1 avanzando satisfactoriamente, con un progreso del 70 por ciento.<\/p>\n\n\n\n<p>Respecto a las fugas atribuidas a la presi\u00f3n, en las l\u00edneas de conducci\u00f3n, se\u00f1al\u00f3 que son constantes, por lo que dijo, instar\u00e1 a la Comisi\u00f3n Nacional del Agua a destinar recursos para abordar este problema, lo que contribuir\u00e1 a prevenir incidentes relacionados con las l\u00edneas obsoletas en el centro de la ciudad.<\/p>\n\n\n\n<p>Tambi\u00e9n expres\u00f3 su preocupaci\u00f3n por la regularizaci\u00f3n y supervisi\u00f3n de los pozos de agua en el municipio, destacando la sobreexplotaci\u00f3n como una preocupaci\u00f3n real. Anunci\u00f3 que a trav\u00e9s del SAPAL se realizar\u00e1 una solicitud para llevar a cabo una revisi\u00f3n exhaustiva de pozos, lo que sin duda mejorar\u00e1 significativamente el suministro de agua en diversas zonas rurales como Nazareno, La Luz y La Mina.<\/p>\n\n\n\n<p>_ 2271_<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(INFORMATIVO) FECHA: 11\/04\/2024 Este jueves, el Alcalde de Lerdo, Homero Mart\u00ednez Cabrera inform\u00f3 que, actualmente, el Sistema de Agua Potable y Alcantarillado de Lerdo (SAPAL) recibe un caudal de 450 litros por segundo, proveniente del Proyecto de Agua Saludable para la Laguna (ASL). \u201cHemos colaborado activamente con el mencionado proyecto, siendo el municipio piloto. Hemos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35263"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=35263"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35263\/revisions"}],"predecessor-version":[{"id":35265,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35263\/revisions\/35265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/35264"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=35263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=35263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=35263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}