{"id":35266,"date":"2024-04-11T18:48:53","date_gmt":"2024-04-12T00:48:53","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=35266"},"modified":"2024-04-11T18:48:54","modified_gmt":"2024-04-12T00:48:54","slug":"ficha-tecnica-no-132-tema-cabildo-74","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/04\/11\/ficha-tecnica-no-132-tema-cabildo-74\/","title":{"rendered":"FICHA T\u00c9CNICA NO. 132 TEMA CABILDO 74"},"content":{"rendered":"\n<p>(INFORMATIVO)<\/p>\n\n\n\n<p>FECHA: 11\/04\/2024<\/p>\n\n\n\n<p>Esta ma\u00f1ana se desarroll\u00f3 la sesi\u00f3n Ordinaria de Cabildo n\u00famero 74, en el Sal\u00f3n Azul de la Presidencia Municipal de Lerdo, Durango. Posterior a la aprobaci\u00f3n del orden del d\u00eda, el Alcalde Homero Mart\u00ednez Cabrera escuch\u00f3 las intervenciones de los regidores en \u2018Asuntos Generales\u2019 y dio respuesta.<\/p>\n\n\n\n<p>Se abordaron temas de seguridad vial, movilidad, atenci\u00f3n ciudadana, alumbrado p\u00fablico, servicios de agua potable, bacheo, drenaje, as\u00ed como la revisi\u00f3n de propuestas de ba\u00f1os ecol\u00f3gicos y plantaci\u00f3n de 2 \u00e1rboles por vivienda en fraccionamientos.<\/p>\n\n\n\n<p>En primera instancia, dijo que la Comisi\u00f3n de Tr\u00e1nsito y Vialidad deber\u00e1 hacer una revisi\u00f3n minuciosa, respecto a la propuesta de modificaci\u00f3n de la calle Chihuahua (entre boulevard Miguel Hidalgo y avenida Durango), basado en el an\u00e1lisis de impacto vial, oficio recibido en la Correspondencia de Cabildo, con el fin de mejorar la movilidad en dicho sector.<\/p>\n\n\n\n<p>Agreg\u00f3 que en el ejido La Luz, se han iniciado las acciones de mantenimiento en el c\u00e1rcamo de la comunidad, mismas que se integran en la propuesta de obra 2024. As\u00ed como la proyecci\u00f3n de recarpeteo y finalizar el tramo carretero de la vialidad de La Luz rumbo a La Mina.<\/p>\n\n\n\n<p>La propuesta de la Secretar\u00eda de Infraestructura, Comunicaciones y Transportes (SICT) para la ampliaci\u00f3n a cuatro carriles del tramo carretero de la entrada principal en La Loma y el mantenimiento en pozos de agua para estabilizaci\u00f3n del suministro, tambi\u00e9n fueron temas que se dialogaron en \u2018Asuntos Generales\u2019.<\/p>\n\n\n\n<p>2272<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(INFORMATIVO) FECHA: 11\/04\/2024 Esta ma\u00f1ana se desarroll\u00f3 la sesi\u00f3n Ordinaria de Cabildo n\u00famero 74, en el Sal\u00f3n Azul de la Presidencia Municipal de Lerdo, Durango. Posterior a la aprobaci\u00f3n del orden del d\u00eda, el Alcalde Homero Mart\u00ednez Cabrera escuch\u00f3 las intervenciones de los regidores en \u2018Asuntos Generales\u2019 y dio respuesta. Se abordaron temas de seguridad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35266"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=35266"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35266\/revisions"}],"predecessor-version":[{"id":35268,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/35266\/revisions\/35268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/35267"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=35266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=35266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=35266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}