{"id":40134,"date":"2024-09-22T16:08:08","date_gmt":"2024-09-22T22:08:08","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=40134"},"modified":"2024-09-22T16:08:10","modified_gmt":"2024-09-22T22:08:10","slug":"ayuntamiento-de-gomez-palacio-brinda-platicas-matrimoniales-a-traves-del-dif","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/09\/22\/ayuntamiento-de-gomez-palacio-brinda-platicas-matrimoniales-a-traves-del-dif\/","title":{"rendered":"Ayuntamiento de G\u00f3mez Palacio brinda pl\u00e1ticas matrimoniales a trav\u00e9s del DIF"},"content":{"rendered":"\n<p>El Ayuntamiento de G\u00f3mez Palacio a trav\u00e9s del Sistema para el Desarrollo Integral de la Familia (DIF), ofrece pl\u00e1ticas matrimoniales los d\u00edas viernes de cada semana, logrando atender en lo que va del a\u00f1o a m\u00e1s de 400 y cumplir con ello el requisito obligatorio, establecido por el registro civil.<\/p>\n\n\n\n<p>La Presidenta Municipal Leticia Herrera Ale ha instruido al DIF municipal proporcionar herramientas que contribuyan a formar matrimonios s\u00f3lidos. Durante las pl\u00e1ticas, se abordan temas como la comunicaci\u00f3n asertiva, resoluci\u00f3n de conflictos y nuevas responsabilidades derivadas del matrimonio.<\/p>\n\n\n\n<p>Brenda Calder\u00f3n Carrete, directora del DIF, se\u00f1al\u00f3 que estas pl\u00e1ticas fortalecen los matrimonios al brindarles herramientas para enfrentar los retos de esta nueva etapa. Para casarse, las parejas deben asistir a estas pl\u00e1ticas y obtener una constancia, que tiene un costo simb\u00f3lico de 50 pesos, requerida por la Oficial\u00eda del Registro Civil.<\/p>\n\n\n\n<p>Las sesiones son impartidas por el Departamento de Fortalecimiento Familiar, Humano y de Valores del DIF, en el Club de Ni\u00f1os, Ni\u00f1as y Adolescentes, ubicado en Av. Central S\/N, colonia Valle de Chapala, de 9:00 a 12:00 horas. Los interesados deben presentar dos copias del INE y un comprobante de domicilio. Para m\u00e1s informaci\u00f3n, pueden llamar a los tel\u00e9fonos 8717 14 92 86 y 8717 14 21 27.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de G\u00f3mez Palacio a trav\u00e9s del Sistema para el Desarrollo Integral de la Familia (DIF), ofrece pl\u00e1ticas matrimoniales los d\u00edas viernes de cada semana, logrando atender en lo que va del a\u00f1o a m\u00e1s de 400 y cumplir con ello el requisito obligatorio, establecido por el registro civil. La Presidenta Municipal Leticia Herrera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/40134"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=40134"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/40134\/revisions"}],"predecessor-version":[{"id":40136,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/40134\/revisions\/40136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/40135"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=40134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=40134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=40134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}