{"id":40158,"date":"2024-09-23T18:39:43","date_gmt":"2024-09-24T00:39:43","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=40158"},"modified":"2024-10-03T21:01:33","modified_gmt":"2024-10-04T03:01:33","slug":"municipio-de-torreon-recibe-certificacion-por-el-cumplimiento-al-programa-de-reconocimiento-y-operacion-sare-prosare","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/09\/23\/municipio-de-torreon-recibe-certificacion-por-el-cumplimiento-al-programa-de-reconocimiento-y-operacion-sare-prosare\/","title":{"rendered":"Municipio de Torre\u00f3n recibe certificaci\u00f3n por el cumplimiento al Programa de Reconocimiento y Operaci\u00f3n SARE (PROSARE)"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 24 de septiembre de 2024La Administraci\u00f3n Municipal encabezada por el alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, a trav\u00e9s de la Direcci\u00f3n General de Desarrollo Institucional, recibi\u00f3 la Certificaci\u00f3n Nacional por su calificaci\u00f3n sobresaliente en el cumplimiento del Programa de Reconocimiento y Operaci\u00f3n SARE (PROSARE).Lo anterior es otorgado por la Comisi\u00f3n Nacional de Mejora Regulatoria (CONAMER), a aquellos municipios que cuentan con un sistema de apertura r\u00e1pida de empresas, cuyas licencias de bajo riesgo son expedidas de acuerdo a los tiempos y la normativa establecida por dicha instituci\u00f3n federal.Gustavo Mu\u00f1oz L\u00f3pez, director de la dependencia municipal, dio a conocer que Torre\u00f3n logr\u00f3 una buena calificaci\u00f3n luego del proceso de evaluaci\u00f3n realizado por la CONAMER el a\u00f1o pasado, en el que se demostr\u00f3 que las licencias de funcionamiento SARE son expedidas de forma inmediata y sin necesidad de inspecciones previas.Destac\u00f3 adem\u00e1s que la renovaci\u00f3n de dichas licencias se puede llevar a cabo de forma totalmente digital, cumpli\u00e9ndose con los objetivos de la mejora regulatoria, que busca disminuir el costo social de tr\u00e1mites y servicios, es decir, el precio que representa para los ciudadanos en tiempo, traslados, papeler\u00eda, entre otros.Indic\u00f3 que el trabajo es realizado de forma coordinada por el \u00e1rea de Calidad y Mejora Regulatoria de la direcci\u00f3n, a cargo de Rafael Olivares Garc\u00eda, y Ventanilla \u00danica de la Direcci\u00f3n General de Desarrollo Econ\u00f3mico a cargo de Rosalinda Gurza Jaidar.El funcionario mencion\u00f3 que actualmente s\u00f3lo cuentan con esta distinci\u00f3n tres municipios de Coahuila, Saltillo, Piedras Negras y Torre\u00f3n.Dio a conocer que el reconocimiento fue entregado por Alberto Montoya Mart\u00edn del Campo, titular de la Comisi\u00f3n Nacional de Mejora Regulatoria (CONAMER).-Torre\u00f3n \u00a1Siempre Puede! &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 24 de septiembre de 2024La Administraci\u00f3n Municipal encabezada por el alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, a trav\u00e9s de la Direcci\u00f3n General de Desarrollo Institucional, recibi\u00f3 la Certificaci\u00f3n Nacional por su calificaci\u00f3n sobresaliente en el cumplimiento del Programa de Reconocimiento y Operaci\u00f3n SARE (PROSARE).Lo anterior es otorgado por la Comisi\u00f3n Nacional de Mejora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/40158"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=40158"}],"version-history":[{"count":2,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/40158\/revisions"}],"predecessor-version":[{"id":40449,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/40158\/revisions\/40449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/40159"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=40158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=40158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=40158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}