{"id":41015,"date":"2024-10-17T19:05:57","date_gmt":"2024-10-18T01:05:57","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=41015"},"modified":"2024-10-17T19:05:58","modified_gmt":"2024-10-18T01:05:58","slug":"conmemoran-en-lerdo-el-71-aniversario-del-sufragio-femenino","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/10\/17\/conmemoran-en-lerdo-el-71-aniversario-del-sufragio-femenino\/","title":{"rendered":"CONMEMORAN EN LERDO EL 71 ANIVERSARIO DEL SUFRAGIO FEMENINO"},"content":{"rendered":"\n<p>*Lerdo, 17 de octubre 2024.\u2013 En una emotiva ceremonia celebrada la ma\u00f1ana de este jueves, el Instituto Municipal de la Mujer conmemor\u00f3 el 71 aniversario del Sufragio Femenino en la plazuela Benito Ju\u00e1rez, frente al busto de Hermila Galindo, destacada figura en la lucha por los derechos de las mujeres en M\u00e9xico.El evento cont\u00f3 con la representaci\u00f3n del Presidente Municipal Homero Mart\u00ednez Cabrera, a trav\u00e9s del Secretario T\u00e9cnico del Ayuntamiento, Ram\u00f3n Acosta Barrios, quien reconoci\u00f3 el trabajo del Alcalde durante su administraci\u00f3n, brindando puestos importantes para las mujeres en el Gobierno Municipal. Y, agreg\u00f3 que, gracias a que la mujer ahora puede ser votada para diversos cargos pol\u00edticos, en el municipio de Lerdo se cuenta con m\u00e1s del 50% de mujeres integrando el Cabildo. El director de Museograf\u00eda, Baltazar Torres S\u00e1nchez, ofreci\u00f3 una remembranza sobre la historia del sufragio femenino en M\u00e9xico, formalmente instituido en 1953, el cual representa un triunfo hist\u00f3rico que permiti\u00f3 a las mujeres participar en la vida pol\u00edtica y social del pa\u00eds. Record\u00f3 que figuras como Hermila Galindo, quien fue una pionera en la lucha por los derechos de las mujeres en la d\u00e9cada de 1920, desempe\u00f1aron un papel fundamental en este proceso. Galindo no solo abog\u00f3 por el derecho al voto, sino que tambi\u00e9n promovi\u00f3 la educaci\u00f3n y la salud de las mujeres, sentando las bases para un movimiento que contin\u00faa luchando por la igualdad.La conmemoraci\u00f3n en Lerdo no solo celebr\u00f3 un pasado significativo, sino que tambi\u00e9n sirvi\u00f3 como un recordatorio del trabajo que a\u00fan queda por hacer en la b\u00fasqueda de la igualdad de g\u00e9nero y el empoderamiento de las mujeres en todos los \u00e1mbitos de la sociedad. La directora del IMM, Mar\u00eda del Refugio Adame G\u00fcereca, agradeci\u00f3 la presencia y participaci\u00f3n de las autoridades municipales, regidores, as\u00ed como asociaciones civiles y escuelas.Donde se cont\u00f3 con la asistencia de la delegada de la procuradur\u00eda de protecci\u00f3n de ni\u00f1os, ni\u00f1as y adolescentes, Laura Meraz; la coordinadora del programa Esmeralda, Ana Isabel Villegas; la fundadora de Musas, Ma Evangelina Vel\u00e1zquez; la directora del Centro de Integraci\u00f3n Juvenil Laguna Durango A.C., Blanca Ruvalcaba; el coordinador del \u00e1rea de Prevenci\u00f3n Social, Mario Romero; la Dra. Araceli D\u00edaz Guzm\u00e1n, directora del centro de salud Roberto Garc\u00eda Sosa de la Vi\u00f1a; estudiantes del Colegio Lerdo Contempor\u00e1neo y su director, Antonio de Jes\u00fas Gonz\u00e1lez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Lerdo, 17 de octubre 2024.\u2013 En una emotiva ceremonia celebrada la ma\u00f1ana de este jueves, el Instituto Municipal de la Mujer conmemor\u00f3 el 71 aniversario del Sufragio Femenino en la plazuela Benito Ju\u00e1rez, frente al busto de Hermila Galindo, destacada figura en la lucha por los derechos de las mujeres en M\u00e9xico.El evento cont\u00f3 con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41015"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=41015"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41015\/revisions"}],"predecessor-version":[{"id":41017,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41015\/revisions\/41017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/41016"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=41015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=41015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=41015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}