{"id":41171,"date":"2024-10-21T22:09:59","date_gmt":"2024-10-22T04:09:59","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=41171"},"modified":"2024-10-21T22:10:00","modified_gmt":"2024-10-22T04:10:00","slug":"recibe-alcaldesa-leticia-herrera-ale-donativo-de-dos-drones","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/10\/21\/recibe-alcaldesa-leticia-herrera-ale-donativo-de-dos-drones\/","title":{"rendered":"Recibe Alcaldesa Leticia Herrera Ale donativo de dos drones"},"content":{"rendered":"\n<p>Por parte de 7-Eleven\/Petro-7 destinados a fortalecer las labores de vigilancia del municipio, como una muestra m\u00e1s de la confianza que la iniciativa privada tiene hacia la administraci\u00f3n que encabeza la Presidenta Municipal Leticia Herrera Ale, la empresa 7-Eleven\/Petro-7 don\u00f3 al Ayuntamiento 2 dones para que la Direcci\u00f3n de Seguridad P\u00fablica Municipal cuente con m\u00e1s equipamiento para el cumplimiento de sus funciones.En un evento realizado en el Auditorio Benito Ju\u00e1rez de la Presidencia Municipal de G\u00f3mez Palacio, la alcaldesa expres\u00f3 que estos drones fortalecen las labores preventivas y permitir\u00e1n una mejor capacidad de reacci\u00f3n ante determinadas circunstancias en que tener una visi\u00f3n a\u00e9rea facilita el trabajo de la corporaci\u00f3n municipal.Ram\u00f3n Francisco Le\u00f3n L\u00f3pez, gerente de Relaciones Institucionales de 7-Eleven\/Petro-7, fue el encargado de entregar los dos drones, y al hacerlo destac\u00f3 el compromiso que su empresa tiene con el bienestar de la comunidad, por ello realizan este donativo, pues ellos mismos pueden atestiguar, el compromiso que tienen los elementos de la polic\u00eda municipal de G\u00f3mez Palacio, cada vez que han realizado un llamado de ayuda. La Presidenta Municipal Leticia Herrera Ale agradeci\u00f3 el apoyo: \u201cMe da mucho gusto saber que la iniciativa privada est\u00e1 siempre dispuesta a apoyarnos; empresas como 7-Eleven\/Petro-7 son un ejemplo de que, en equipo, podemos construir la sociedad que todos deseamos, por ello recibimos con mucha satisfacci\u00f3n este donativo\u201d.Este tipo de medidas fortalecen la estrategia de seguridad que de manera coordinada con el Ej\u00e9rcito Nacional, Guardia Nacional, Mando Especial, as\u00ed como las corporaciones Estatales de seguridad, han permitido una significativa reducci\u00f3n en los \u00edndices delictivos desde que inici\u00f3 la presente administraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por parte de 7-Eleven\/Petro-7 destinados a fortalecer las labores de vigilancia del municipio, como una muestra m\u00e1s de la confianza que la iniciativa privada tiene hacia la administraci\u00f3n que encabeza la Presidenta Municipal Leticia Herrera Ale, la empresa 7-Eleven\/Petro-7 don\u00f3 al Ayuntamiento 2 dones para que la Direcci\u00f3n de Seguridad P\u00fablica Municipal cuente con m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41171"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=41171"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41171\/revisions"}],"predecessor-version":[{"id":41173,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41171\/revisions\/41173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/41172"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=41171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=41171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=41171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}