{"id":41328,"date":"2024-10-25T22:14:50","date_gmt":"2024-10-26T04:14:50","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=41328"},"modified":"2024-10-25T22:14:52","modified_gmt":"2024-10-26T04:14:52","slug":"ayuntamiento-de-gomez-palacio-intensifica-esfuerzos-para-mejorar-el-alumbrado-publico","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/10\/25\/ayuntamiento-de-gomez-palacio-intensifica-esfuerzos-para-mejorar-el-alumbrado-publico\/","title":{"rendered":"Ayuntamiento de G\u00f3mez Palacio intensifica esfuerzos para mejorar el alumbrado p\u00fablico"},"content":{"rendered":"\n<p>*En un esfuerzo continuo por mantener en \u00f3ptimas condiciones el alumbrado p\u00fablico del municipio, el Ayuntamiento de G\u00f3mez Palacio, a trav\u00e9s de la Direcci\u00f3n de Servicios P\u00fablicos, est\u00e1 intensificando sus recorridos para identificar y reparar fallas en este sistema, poniendo especial atenci\u00f3n en d\u00edas pasados a las colonias Los \u00c1lamos, Miravalle, Haciendas el Refugio y Filadelfia.Fernando D\u00edaz Femath, titular de la Direcci\u00f3n de Servicios P\u00fablicos, destac\u00f3 que estas acciones son esenciales para la administraci\u00f3n de la Presidenta Municipal Leticia Herrera Ale, quien desde el inicio de su administraci\u00f3n, se ha enfocado en revitalizar un sistema de alumbrado que se encontraba en muy malas condiciones. \u201cHoy, gracias a esfuerzos continuos, G\u00f3mez Palacio disfruta de un alumbrado p\u00fablico con muy pocas fallas que lamentablemente en su mayor\u00eda provienen de situaciones derivadas de actos de vandalismo\u201d, explic\u00f3 D\u00edaz Femath.El funcionario subray\u00f3 la importancia de la colaboraci\u00f3n ciudadana en este proceso y exhort\u00f3 a la comunidad a reportar cualquier actividad sospechosa que pueda afectar la infraestructura p\u00fablica. Adem\u00e1s, resalt\u00f3 la cooperaci\u00f3n estrecha con la Direcci\u00f3n de Seguridad P\u00fablica y Protecci\u00f3n Ciudadana, lo que ha permitido avanzar significativamente en la resoluci\u00f3n de estos problemas.Para facilitar la comunicaci\u00f3n y reporte de incidencias, la ciudadan\u00eda puede utilizar los n\u00fameros de contacto 871 714 03 17, disponibles para reportes sobre fallas en el alumbrado p\u00fablico.El Ayuntamiento de G\u00f3mez Palacio reitera su compromiso de colaborar con la comunidad para garantizar un entorno seguro y adecuadamente iluminado para todos los ciudadanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*En un esfuerzo continuo por mantener en \u00f3ptimas condiciones el alumbrado p\u00fablico del municipio, el Ayuntamiento de G\u00f3mez Palacio, a trav\u00e9s de la Direcci\u00f3n de Servicios P\u00fablicos, est\u00e1 intensificando sus recorridos para identificar y reparar fallas en este sistema, poniendo especial atenci\u00f3n en d\u00edas pasados a las colonias Los \u00c1lamos, Miravalle, Haciendas el Refugio y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41328"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=41328"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41328\/revisions"}],"predecessor-version":[{"id":41330,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/41328\/revisions\/41330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/41329"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=41328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=41328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=41328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}