{"id":42476,"date":"2024-12-10T22:39:15","date_gmt":"2024-12-11T04:39:15","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=42476"},"modified":"2024-12-10T22:39:17","modified_gmt":"2024-12-11T04:39:17","slug":"administracion-municipal-logra-un-promedio-de-99-73-en-cumplimiento-de-transparencia-ante-el-icai","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2024\/12\/10\/administracion-municipal-logra-un-promedio-de-99-73-en-cumplimiento-de-transparencia-ante-el-icai\/","title":{"rendered":"Administraci\u00f3n Municipal logra un promedio de 99.73 en cumplimiento de transparencia ante el ICAI"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p> Torre\u00f3n, Coahuila. A 10 de diciembre de 2024<\/p>\n\n\n\n<p>La Administraci\u00f3n Municipal a trav\u00e9s de la Unidad de Transparencia, logr\u00f3 un cumplimiento del 99.73 por ciento en la evaluaci\u00f3n hecha por el Instituto Coahuilense de Acceso a la Informaci\u00f3n P\u00fablica (ICAI), durante los 11 trimestres que el organismo emiti\u00f3 su calificaci\u00f3n.Marbil Valdez Rodr\u00edguez, titular de la Unidad de Transparencia en Torre\u00f3n, dio a conocer este martes a regidores del Ayuntamiento, el informe semestral de actividades, en el que destac\u00f3 las estrategias de la Administraci\u00f3n Municipal para fomentar la participaci\u00f3n ciudadana.La funcionaria indic\u00f3 que durante el tercer trimestre del presente a\u00f1o, la direcci\u00f3n concluy\u00f3 con el cumplimiento del 100 por ciento, en cuanto a la Informaci\u00f3n P\u00fablica de Oficio (IPO).Por otra parte, indic\u00f3 que de las solicitudes realizadas por la ciudadan\u00eda durante este a\u00f1o.\u201cSe llevaron a cabo 821 solicitudes de acceso a la informaci\u00f3n, de las cuales 723 se realizaron a trav\u00e9s de la Plataforma Nacional de Transparencia (PNT) y 98 de manera presencial\u201d, detall\u00f3.Destac\u00f3 que durante la presente Administraci\u00f3n se llevaron a cabo estrategias para la mejora de la transparencia y para fomentar la participaci\u00f3n ciudadana.Lo anterior a trav\u00e9s del programa \u201cTorre\u00f3n Transparente\u201d, y la creaci\u00f3n de c\u00f3digos QR para facilitar a la ciudadan\u00eda el acceso a la informaci\u00f3n p\u00fablica de su inter\u00e9s que genera el Gobierno Municipal.Lo anterior fue dado a conocer durante la trig\u00e9sima cuarta sesi\u00f3n de la Comisi\u00f3n de Transparencia y Acceso a la Informaci\u00f3n P\u00fablica, presidida por la s\u00edndica M\u00f3nica Montero Cu\u00e9llar, e integrada por los regidores Jos\u00e9 Arturo Rangel Peralta, Amira Lucia Darwich Garc\u00eda, Karla Liliana Centeno F\u00e9lix, Omar Morales Rodr\u00edguez, Alma Lucina Fong Mel\u00e9ndez y Zazil Pacheco P\u00e9rez.-Torre\u00f3n \u00a1Siempre Puede! &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 10 de diciembre de 2024 La Administraci\u00f3n Municipal a trav\u00e9s de la Unidad de Transparencia, logr\u00f3 un cumplimiento del 99.73 por ciento en la evaluaci\u00f3n hecha por el Instituto Coahuilense de Acceso a la Informaci\u00f3n P\u00fablica (ICAI), durante los 11 trimestres que el organismo emiti\u00f3 su calificaci\u00f3n.Marbil Valdez Rodr\u00edguez, titular de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/42476"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=42476"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/42476\/revisions"}],"predecessor-version":[{"id":42478,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/42476\/revisions\/42478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/42477"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=42476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=42476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=42476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}