{"id":43018,"date":"2025-01-05T16:25:33","date_gmt":"2025-01-05T22:25:33","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=43018"},"modified":"2025-01-05T16:25:34","modified_gmt":"2025-01-05T22:25:34","slug":"instalados-comites-de-evaluacion-de-los-poderes-ejecutivo-legislativo-y-judicial-en-coahuila","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2025\/01\/05\/instalados-comites-de-evaluacion-de-los-poderes-ejecutivo-legislativo-y-judicial-en-coahuila\/","title":{"rendered":"INSTALADOS COMIT\u00c9S DE EVALUACI\u00d3N DE LOS PODERES EJECUTIVO, LEGISLATIVO Y JUDICIAL EN COAHUILA"},"content":{"rendered":"\n<p>  El Gobierno del Estado de Coahuila, a trav\u00e9s de la Secretar\u00eda de Gobierno, dio a conocer la conformaci\u00f3n del Comit\u00e9 de Evaluaci\u00f3n del Poder Ejecutivo para la selecci\u00f3n  y elegibilidad de quienes deseen participar como candidatas y candidatos para la elecci\u00f3n de Magistraturas y titulares de Juzgados en Coahuila.  Se trata de: * El cronista de Saltillo, Armando Fuentes Aguirre, \u00abCat\u00f3n\u00bb, destacado abogado, periodista y humanista coahuilense con amplia trayectoria en el servicio p\u00fablico y representante del sector acad\u00e9mico del estado, entre su trayectoria destaca haber sido director del Ateneo Fuente y de la Facultad de Ciencias de la Comunicaci\u00f3n de la Universidad Aut\u00f3noma de Coahuila, quien tendr\u00e1 el cargo de Presidente Honor\u00edfico del comit\u00e9. * La abogada Luz Mar\u00eda Diez de Urdanivia Del Valle, Presidenta del Colegio de Notarios de Coahuila, con amplia trayectoria jur\u00eddica, tanto en el servicio p\u00fablico, como en la academia. * El Jefe de Gabinete y Proyectos Estrat\u00e9gicos del Gobierno del Estado de Coahuila, el maestro Blas Flores Gonz\u00e1lez, quien encabeza dentro de la administraci\u00f3n estatal el desarrollo y continuidad de pol\u00edticas p\u00fablicas. De esta manera, el Comit\u00e9 de Evaluaci\u00f3n del Poder Ejecutivo, se suma a los comit\u00e9s del Poder Legislativo, conformado por el rector de la UANE, Giovani de la Pe\u00f1a Merlos, el notario Francisco de Le\u00f3n Tello y la abogada Elizabeth Colchado Galindo; y del Poder Judicial, el cual est\u00e1 integrado por la Presidenta de la Asociaci\u00f3n de Licenciadas en Derecho de Coahuila, Rebeca Boone Villarreal; el Secretario General de la Universidad Aut\u00f3noma de Coahuila, V\u00edctor Manuel S\u00e1nchez Vald\u00e9s y Armando Mercado Hern\u00e1ndez, Director General Acad\u00e9mico de la Universidad Iberoamericana, campus Torre\u00f3n. Con la instalaci\u00f3n de los comit\u00e9s de los tres \u00f3rdenes de gobierno de Coahuila se da cumplimiento en tiempo y forma a las acciones requeridas para la elegibilidad de los perfiles que participar\u00e1n en Coahuila, de acuerdo a la Reforma del Poder Judicial, el pr\u00f3ximo mes de junio para la elecci\u00f3n de jueces y magistrados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno del Estado de Coahuila, a trav\u00e9s de la Secretar\u00eda de Gobierno, dio a conocer la conformaci\u00f3n del Comit\u00e9 de Evaluaci\u00f3n del Poder Ejecutivo para la selecci\u00f3n y elegibilidad de quienes deseen participar como candidatas y candidatos para la elecci\u00f3n de Magistraturas y titulares de Juzgados en Coahuila. Se trata de: * El cronista [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43018"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=43018"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43018\/revisions"}],"predecessor-version":[{"id":43020,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43018\/revisions\/43020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/43019"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=43018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=43018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=43018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}