{"id":5441,"date":"2022-10-14T18:31:53","date_gmt":"2022-10-14T18:31:53","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=5441"},"modified":"2022-10-14T18:31:57","modified_gmt":"2022-10-14T18:31:57","slug":"toma-protesta-leticia-herrera-a-integrantes-de-copladem-para-el-periodo-2022-2025","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2022\/10\/14\/toma-protesta-leticia-herrera-a-integrantes-de-copladem-para-el-periodo-2022-2025\/","title":{"rendered":"Toma protesta Leticia Herrera a integrantes de Copladem para el periodo 2022-2025"},"content":{"rendered":"\n<p>La presidenta municipal, Leticia Herrera Ale, tom\u00f3 protesta a los integrantes del Comit\u00e9 de Planeaci\u00f3n para el Desarrollo Municipal (Copladem), a fin de dar cumplimiento a la Ley de administraci\u00f3n de las aportaciones federales transferidas al Estado de Durango y sus Municipios, en este caso al municipio de G\u00f3mez Palacio.<br>Dicho comit\u00e9 ser\u00e1 presidido por la alcaldesa, Leticia Herrera Ale; mientras que Yadira Jazm\u00edn Lara Reyes, asume la coordinaci\u00f3n del Copladem; mientras que Brenda Cristal Contreras toma la responsabilidad de la Secretar\u00eda T\u00e9cnica; a ellos se suman integrantes del Ayuntamiento de G\u00f3mez Palacio, funcionarios de dependencias del Gobierno Federal, Estatal y Municipal, adem\u00e1s de representantes de organismos y c\u00e1maras empresariales.<br>La presidenta municipal, Leticia Herrera expuso que la funci\u00f3n de los miembros del Copladem ser\u00e1 la de intervenir de manera directa en la toma de decisiones sobre el ejercicio transparente de recursos que llegan a trav\u00e9s del Fondo Estatal para la Infraestructura Social (FAIS).<br>Dichos recursos servir\u00e1n para la ejecuci\u00f3n de programas o proyectos de agua potable, de rehabilitaci\u00f3n de redes de drenaje y alcantarillado, caminos rurales, obras de pavimentaci\u00f3n, infraestructura y acciones de vivienda.<br>\u201cLa participaci\u00f3n de un \u00f3rgano que garantice el uso de los recursos p\u00fablicos, mediante la transparencia, es fundamental para el desarrollo del municipio y de la ciudadan\u00eda\u201d, se\u00f1al\u00f3 la primera autoridad.<br>Finalmente, la Alcaldesa agradeci\u00f3 la disposici\u00f3n, voluntad e iniciativa de cada uno de los funcionarios y representantes sociales que rindieron protesta, ya que trabajando juntos y en equipo, las obras y acciones ejecutadas con este recurso ser\u00e1n de total apoyo y beneficio para los gomezpalatinos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta municipal, Leticia Herrera Ale, tom\u00f3 protesta a los integrantes del Comit\u00e9 de Planeaci\u00f3n para el Desarrollo Municipal (Copladem), a fin de dar cumplimiento a la Ley de administraci\u00f3n de las aportaciones federales transferidas al Estado de Durango y sus Municipios, en este caso al municipio de G\u00f3mez Palacio.Dicho comit\u00e9 ser\u00e1 presidido por la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5441"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5441"}],"version-history":[{"count":0,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5442"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}