{"id":5469,"date":"2022-10-14T21:55:08","date_gmt":"2022-10-14T21:55:08","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=5469"},"modified":"2022-10-14T21:55:13","modified_gmt":"2022-10-14T21:55:13","slug":"acompana-homero-martinez-a-esteban-villegas-a-la-entrega-de-equipamiento-a-hospitales-generales-de-la-laguna","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2022\/10\/14\/acompana-homero-martinez-a-esteban-villegas-a-la-entrega-de-equipamiento-a-hospitales-generales-de-la-laguna\/","title":{"rendered":"ACOMPA\u00d1A HOMERO MART\u00cdNEZ A ESTEBAN VILLEGAS A LA ENTREGA DE EQUIPAMIENTO A HOSPITALES GENERALES DE LA LAGUNA"},"content":{"rendered":"\n<p>Lerdo, 14 de octubre 2022.- El Presidente Municipal de Lerdo, Homero Mart\u00ednez Cabrera, acompa\u00f1\u00f3 al gobernador del estado Esteban Villegas Villarreal y a la presidenta de G\u00f3mez Palacio Leticia Herrera Ale, a la entrega de equipamiento para los hospitales generales de ambas ciudades, un compromiso cumplido en materia de salud. El evento se llev\u00f3 a cabo en el HG de G\u00f3mez Palacio.<\/p>\n\n\n\n<p>En su discurso, Homero Mart\u00ednez, reconoci\u00f3 la importancia de dotar de instrumentos especializados a los nosocomios de las ciudades para atender a la Comarca Lagunera, y se mostr\u00f3 convencido en que Esteban Villegas har\u00e1 lo conducente para equipar en su totalidad el Hospital General Regional.<\/p>\n\n\n\n<p>\u201cEl hecho de que el gobernador del estado Esteban Villegas, sea m\u00e9dico de profesi\u00f3n, yo estoy cierto en que eso va a ayudar much\u00edsimo a las familias de la regi\u00f3n, pues el contar con este edificio, sin duda, ser\u00e1 de gran ayuda para la zona conurbada de La Laguna\u201d.<\/p>\n\n\n\n<p>De igual forma, la Alcaldesa de G\u00f3mez Palacio, agradeci\u00f3 al gobernador del estado por cumplir cada uno de sus compromisos con los habitantes de la Comarca Lagunera.<\/p>\n\n\n\n<p>Para finalizar, Esteban Villegas se comprometi\u00f3 en atender a los laguneros en el tema de salud y adelant\u00f3 que el Hospital General de ciudad de Lerdo, tambi\u00e9n ser\u00e1 equipado en un corto plazo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lerdo, 14 de octubre 2022.- El Presidente Municipal de Lerdo, Homero Mart\u00ednez Cabrera, acompa\u00f1\u00f3 al gobernador del estado Esteban Villegas Villarreal y a la presidenta de G\u00f3mez Palacio Leticia Herrera Ale, a la entrega de equipamiento para los hospitales generales de ambas ciudades, un compromiso cumplido en materia de salud. El evento se llev\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5469"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5469"}],"version-history":[{"count":0,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5470"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}