{"id":5487,"date":"2022-10-15T00:22:10","date_gmt":"2022-10-15T00:22:10","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=5487"},"modified":"2022-10-15T00:22:14","modified_gmt":"2022-10-15T00:22:14","slug":"reactiva-esteban-aplicacion-de-vacuna-anti-covid-para-ninos","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2022\/10\/15\/reactiva-esteban-aplicacion-de-vacuna-anti-covid-para-ninos\/","title":{"rendered":"Reactiva Esteban aplicaci\u00f3n de vacuna anti COVID para ni\u00f1os"},"content":{"rendered":"\n<ul><li>Del 24 al 29 de octubre se aplicar\u00e1n segundas dosis a menores de 5 a 11 a\u00f1os en las instalaciones de la FENADU.<\/li><li>En coordinaci\u00f3n con la Secretar\u00eda de Bienestar y Sedena, se iniciar\u00e1 en algunos municipios con las primeras inmunizaciones.<\/li><\/ul>\n\n\n\n<p>En Durango reiniciamos la aplicaci\u00f3n de primeras y segundas dosis de la vacuna contra COVID-19 para ni\u00f1os de 5 a 11 a\u00f1os de edad, inform\u00f3 el gobernador Esteban Villegas Villarreal al compartir las sedes en municipios y fechas en las que los menores podr\u00e1n ser vacunados, esto gracias a la coordinaci\u00f3n con la Secretar\u00eda de Bienestar y la Secretar\u00eda de la Defensa Nacional (Sedena).<\/p>\n\n\n\n<p>Sobre este tema, la secretaria de Salud, Irasema Kondo Padilla, detall\u00f3 que, del 24 al 29 de octubre, iniciar\u00e1 la aplicaci\u00f3n de la segunda dosis en la capital duranguense, la sede ser\u00e1 la Feria Nacional Durango; el lunes 24 en un horario de 11:00 a 17:00 horas y las fechas siguientes de 9:00 a 17:00 horas.<\/p>\n\n\n\n<p>A partir de esta semana se empezaron a aplicar primeras dosis en Tamazula, Coneto de Comonfort, San Pedro del Gallo, Ocampo, San Luis del Cordero, San Juan del Rio, Hidalgo, Nuevo Ideal y San Dimas, mientras que, del 17 al 20 se vacunar\u00e1 a los menores de G\u00f3mez Palacio y Lerdo.<\/p>\n\n\n\n<p>La aplicaci\u00f3n de la vacuna se llevar\u00e1 a cabo por orden alfab\u00e9tico para que los padres de familia puedan respetar el horario en el que le corresponde a cada ni\u00f1o, precis\u00f3 la Secretaria al recordar que los requisitos para primera dosis es llevar el pre registro, copia del CURP, identificaci\u00f3n oficial de los padres o tutor y poner mucha atenci\u00f3n en que el ni\u00f1o no tenga ninguna infecci\u00f3n respiratoria.<\/p>\n\n\n\n<p>Para los ni\u00f1os de segunda dosis es muy importante que lleven su comprobante de primera dosis y la identificaci\u00f3n del padre de familia, agreg\u00f3.<\/p>\n\n\n\n<p>Kondo Padilla explic\u00f3 que a\u00fan se tienen algunos casos de COVID-19, los cuales han disminuido con las campa\u00f1as de vacunaci\u00f3n, sin embargo, consider\u00f3 necesario completar el esquema en los infantes, ya que durante la temporada invernal hay m\u00e1s riesgo de contagios de enfermedades respiratorias.<\/p>\n\n\n\n<p>En este sentido, invit\u00f3 a la ciudadan\u00eda a vacunarse contra la influenza, pues con las bajas temperaturas, esta enfermedad puede ocasionar neumon\u00edas, \u201ces mejor inmunizarse y evitar contagios\u201d, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 24 al 29 de octubre se aplicar\u00e1n segundas dosis a menores de 5 a 11 a\u00f1os en las instalaciones de la FENADU. En coordinaci\u00f3n con la Secretar\u00eda de Bienestar y Sedena, se iniciar\u00e1 en algunos municipios con las primeras inmunizaciones. En Durango reiniciamos la aplicaci\u00f3n de primeras y segundas dosis de la vacuna contra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5487"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5487"}],"version-history":[{"count":0,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5488"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}