{"id":5654,"date":"2022-10-17T22:56:53","date_gmt":"2022-10-17T22:56:53","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=5654"},"modified":"2022-10-17T22:56:59","modified_gmt":"2022-10-17T22:56:59","slug":"mejora-mars-infraestructura-educativa-en-coahuila","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2022\/10\/17\/mejora-mars-infraestructura-educativa-en-coahuila\/","title":{"rendered":"MEJORA MARS INFRAESTRUCTURA EDUCATIVA EN COAHUILA"},"content":{"rendered":"\n<ul><li><strong><em>&nbsp;El gobernador Miguel Riquelme entrega techumbre en el Instituto Tecnol\u00f3gico de Torre\u00f3n, con una inversi\u00f3n de 3.81 mdp.<\/em><\/strong><\/li><li><strong><em>En coordinaci\u00f3n con el Municipio, se terminar\u00e1 el estacionamiento de la instituci\u00f3n y el Estado donar\u00e1 30 computadoras.<\/em><\/strong><\/li><\/ul>\n\n\n\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 17 de Octubre de 2022.- El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds entreg\u00f3 al Instituto Tecnol\u00f3gico de Torre\u00f3n una techumbre en la que se invirtieron 3 millones 810 mil pesos, evento en el que reiter\u00f3 que mantener la entidad con seguridad, con desarrollo econ\u00f3mico y con la diversificaci\u00f3n de la econom\u00eda, ha sido fruto del esfuerzo de la sociedad y del Gobierno.<\/p>\n\n\n\n<p>El Mandatario estatal mencion\u00f3 que gracias a la coordinaci\u00f3n con Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, Alcalde de Torre\u00f3n, se podr\u00e1 terminar el estacionamiento de la instituci\u00f3n, y que adem\u00e1s el Estado aportar\u00e1 30 nuevas computadoras para que las y los alumnos tengan las herramientas tecnol\u00f3gicas que merecen.<\/p>\n\n\n\n<p>Riquelme Sol\u00eds dijo identificarse con este sistema y con sus alumnos, pues curs\u00f3 sus estudios en una instituci\u00f3n tecnol\u00f3gica; manifest\u00f3 que hoy las condiciones en la entidad son tales que permiten a las y los egresados quedarse a trabajar en esta tierra.<\/p>\n\n\n\n<p>\u201cEsto ha sido fruto del esfuerzo de la sociedad y del Gobierno, mantener la entidad con seguridad, con desarrollo econ\u00f3mico y, sobre todo, la diversificaci\u00f3n de una econom\u00eda como la nuestra, que por a\u00f1os cada regi\u00f3n ha tenido su vocaci\u00f3n y sustento, y hoy en d\u00eda todas aportan para los sectores productivos\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>De la misma manera, Miguel Riquelme expres\u00f3 que el a\u00f1o entrante en la entidad se empezar\u00e1n a armar autos el\u00e9ctricos y eso generar\u00e1 oportunidades para todas las carreras afines.<\/p>\n\n\n\n<p>Sin embargo, dijo que el sector agroalimentario enfrenta un gran potencial, y que seguir\u00e1 impulsando hasta el \u00faltimo d\u00eda de su Administraci\u00f3n a Coahuila y a su gente.<\/p>\n\n\n\n<p>Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, Alcalde de Torre\u00f3n, reconoci\u00f3 el apoyo del gobernador Miguel Riquelme para La Laguna en materia de educaci\u00f3n superior, toda vez que esta \u00e1rea es un referente a nivel nacional.<\/p>\n\n\n\n<p>\u201cEl Instituto Tecnol\u00f3gico de Torre\u00f3n le puede seguir apostando a la educaci\u00f3n, a los m\u00e1s de 800 alumnos y a su personal docente y administrativo, tengan la seguridad que vamos a seguir poniendo a La Laguna en los ojos de M\u00e9xico y el mundo, con la posibilidad de seguir trabajando con los egresados a trav\u00e9s del Instituto Municipal de Emprendimiento\u201d, coment\u00f3.<\/p>\n\n\n\n<p>Cepeda Gonz\u00e1lez dijo no tener duda que Coahuila seguir\u00e1 siendo fuerte, pues la calidad de sus estudiantes as\u00ed lo manifiesta.<\/p>\n\n\n\n<p>Julio Iv\u00e1n Long Hern\u00e1ndez, titular del Instituto Coahuilense para la Infraestructura F\u00edsica Educativa (ICIFED), explic\u00f3 que para beneficio de 800 estudiantes se invirtieron 3 millones 810 mil 448 pesos en la construcci\u00f3n de un techo estructural, con una dimensi\u00f3n de 22 por 30 metros y sustituci\u00f3n de piso en la plaza c\u00edvica.<\/p>\n\n\n\n<p>\u201cEn ICIFED seguimos comprometidos para dar cumplimiento a cada una de las metas planteadas por el gobernador Miguel Riquelme en materia de infraestructura f\u00edsica educativa para las escuelas de la entidad\u201d, expres\u00f3.<\/p>\n\n\n\n<p>C\u00e9sar Eduardo G\u00f3mez Lugo, presidente de la Sociedad de Alumnos, a nombre de sus compa\u00f1eras y compa\u00f1eros agradeci\u00f3 al Gobernador el apoyo para la realizaci\u00f3n de esta obra.<\/p>\n\n\n\n<p>A esta entrega asistieron, adem\u00e1s, Mario Cepeda Ram\u00edrez, diputado local; Francisco Saracho Navarro, Secretario de Educaci\u00f3n de Coahuila; Jos\u00e9 Omar Sald\u00edvar Correa, titular del Instituto Tecnol\u00f3gico de Torre\u00f3n; adem\u00e1s de funcionarios p\u00fablicos estatales, municipales y comunidad estudiantil del tecnol\u00f3gico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;El gobernador Miguel Riquelme entrega techumbre en el Instituto Tecnol\u00f3gico de Torre\u00f3n, con una inversi\u00f3n de 3.81 mdp. En coordinaci\u00f3n con el Municipio, se terminar\u00e1 el estacionamiento de la instituci\u00f3n y el Estado donar\u00e1 30 computadoras. Torre\u00f3n, Coahuila de Zaragoza; a 17 de Octubre de 2022.- El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds entreg\u00f3 al Instituto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5654"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5654"}],"version-history":[{"count":0,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5655"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}