{"id":5670,"date":"2022-10-17T23:18:59","date_gmt":"2022-10-17T23:18:59","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=5670"},"modified":"2022-10-17T23:19:04","modified_gmt":"2022-10-17T23:19:04","slug":"culmina-taller-mecanismos-de-acceso-a-la-justicia-dirigido-a-ciudadanos-de-saltillo","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2022\/10\/17\/culmina-taller-mecanismos-de-acceso-a-la-justicia-dirigido-a-ciudadanos-de-saltillo\/","title":{"rendered":"CULMINA TALLER MECANISMOS DE ACCESO A LA JUSTICIA, DIRIGIDO A CIUDADANOS DE SALTILLO"},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 17 de Octubre de 2022.- Con el objetivo de ampliar sus conocimientos en temas de justicia, inclusi\u00f3n, igualdad y la no discriminaci\u00f3n, finaliz\u00f3 el taller Mecanismos de Acceso a la Justicia realizado en el Centro Integral de Prevenci\u00f3n y Desarrollo Ciudadano Valle Verde.<\/p>\n\n\n\n<p>Luisa Ivone Gallegos Mart\u00ednez, titular de la Direcci\u00f3n de Prevenci\u00f3n Social de la Violencia y la Delincuencia de la Secretar\u00eda de Gobierno de Coahuila, coment\u00f3 que de forma coordinada con la Secretar\u00eda de Inclusi\u00f3n y Desarrollo Social (a trav\u00e9s de la Direcci\u00f3n para Promover la Igualdad y Prevenir la Discriminaci\u00f3n) se llev\u00f3 a cabo este curso, con una duraci\u00f3n de 20 horas y donde 42 personas de la comunidad de Valle Verde obtuvieron su constancia de participaci\u00f3n.<\/p>\n\n\n\n<p>\u201cSe brindaron herramientas te\u00f3ricas y pr\u00e1cticas para que ellas y ellos puedan percibir actos de violencia, discriminaci\u00f3n, inclusi\u00f3n e igualdad, adem\u00e1s de ver hasta d\u00f3nde y c\u00f3mo pueden ayudar en una situaci\u00f3n de esa naturaleza\u201d, se\u00f1al\u00f3 la funcionaria estatal.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que con este tipo de pl\u00e1ticas se promueve el ejercicio de la cultura de la legalidad, generando espacios libres de violencia y discriminaci\u00f3n, adem\u00e1s de estar comprometidos con el empoderamiento comunitario de la sociedad coahuilense.<\/p>\n\n\n\n<p><strong>-o0o-<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 17 de Octubre de 2022.- Con el objetivo de ampliar sus conocimientos en temas de justicia, inclusi\u00f3n, igualdad y la no discriminaci\u00f3n, finaliz\u00f3 el taller Mecanismos de Acceso a la Justicia realizado en el Centro Integral de Prevenci\u00f3n y Desarrollo Ciudadano Valle Verde. Luisa Ivone Gallegos Mart\u00ednez, titular de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5670"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5670"}],"version-history":[{"count":0,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5671"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}