{"id":7098,"date":"2022-11-05T02:49:53","date_gmt":"2022-11-05T02:49:53","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=7098"},"modified":"2022-11-05T02:49:56","modified_gmt":"2022-11-05T02:49:56","slug":"alcalde-de-lerdo-asiste-a-reunion-metropolitana-de-seguridad","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2022\/11\/05\/alcalde-de-lerdo-asiste-a-reunion-metropolitana-de-seguridad\/","title":{"rendered":"ALCALDE DE LERDO ASISTE A REUNI\u00d3N METROPOLITANA DE SEGURIDAD"},"content":{"rendered":"\n<p>Lerdo, 04 noviembre 2022.- Una vez que concluy\u00f3 la reuni\u00f3n metropolitana de seguridad en el Mando \u00danico de La Laguna, el Presidente Municipal de Lerdo Homero Mart\u00ednez Cabrera inform\u00f3 que uno de los temas que preocupa y ocupa es la vigilancia durante el Buen Fin.<\/p>\n\n\n\n<p>El mun\u00edcipe record\u00f3 que cada a\u00f1o, en el mes de noviembre, se lleva a cabo el \u2018Buen Fin\u2019 para promover la econom\u00eda local por medio de ofertas y descuentos, por lo que se mantendr\u00e1 una coordinaci\u00f3n con las diferentes corporaciones policiacas para realizar rondines de vigilancia en las zonas comerciales y cajeros autom\u00e1ticos.<\/p>\n\n\n\n<p>Tambi\u00e9n coment\u00f3 que en la pr\u00f3xima reuni\u00f3n de trabajo, se analizar\u00e1 el tema de la homologaci\u00f3n de horarios para la venta y consumo de alcohol, por lo que se\u00f1al\u00f3, en el municipio de Lerdo se mantiene el orden en bares y centros nocturnos en el tema de control.<\/p>\n\n\n\n<p>Por otro lado, en la mesa de Construcci\u00f3n de la Paz en la Regi\u00f3n Laguna, Durango, celebrada en las instalaciones de la Direcci\u00f3n de Seguridad P\u00fablica en el Municipio de Lerdo, las autoridades de las diferentes corporaciones de seguridad acordaron realizar un operativo de vigilancia en las Villas del Municipio de Lerdo, por motivo de las elecciones para la renovaci\u00f3n de las Juntas de Gobierno en el \u00e1rea rural.<\/p>\n\n\n\n<p>La jornada electoral para la renovaci\u00f3n de las juntas de gobierno, se realizar\u00e1 este pr\u00f3ximo domingo 06 de noviembre, en las villas de Juan E. Garc\u00eda, La Loma, Nazareno, Le\u00f3n Guzm\u00e1n y Villa Ju\u00e1rez, en un horario de 8:00 de la ma\u00f1ana a 6:00 de la tarde, para ello se vigilar\u00e1 el traslado de las urnas de las casillas hacia la cabecera municipal.<\/p>\n\n\n\n<p>La mesa de Seguridad estuvo encabezada por el representante de la SEDENA, comandante Juventino Rojas Popoca; el representante de la Guardia Nacional, Juan Manuel Carrillo; el secretario t\u00e9cnico de la mesa, Luis Alfredo Estala; Jos\u00e9 Luis Olivares Guzm\u00e1n, subdirector de Seguridad P\u00fablica en Lerdo; y el secretario del Ayuntamiento, Eduardo Lara Urby.<\/p>\n\n\n\n<p>Tambi\u00e9n se cont\u00f3 con la presencia de representantes de las corporaciones de PEMEX-Salvaguardas, C4, Polic\u00eda Estatal, Centro Nacional de Inteligencia, Seguridad P\u00fablica G\u00f3mez Palacio y los Instituto de la Mujer de Lerdo y G\u00f3mez Palacio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lerdo, 04 noviembre 2022.- Una vez que concluy\u00f3 la reuni\u00f3n metropolitana de seguridad en el Mando \u00danico de La Laguna, el Presidente Municipal de Lerdo Homero Mart\u00ednez Cabrera inform\u00f3 que uno de los temas que preocupa y ocupa es la vigilancia durante el Buen Fin. El mun\u00edcipe record\u00f3 que cada a\u00f1o, en el mes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7098"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7098"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7098\/revisions"}],"predecessor-version":[{"id":7100,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7098\/revisions\/7100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/7099"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}