{"id":7115,"date":"2022-11-05T03:07:54","date_gmt":"2022-11-05T03:07:54","guid":{"rendered":"https:\/\/revistaprogreso.com.mx\/?p=7115"},"modified":"2022-11-05T03:07:57","modified_gmt":"2022-11-05T03:07:57","slug":"roman-alberto-cepeda-gonzalez-reitera-compromiso-con-estudiantes-universitarios","status":"publish","type":"post","link":"https:\/\/revistaprogreso.com.mx\/index.php\/2022\/11\/05\/roman-alberto-cepeda-gonzalez-reitera-compromiso-con-estudiantes-universitarios\/","title":{"rendered":"<strong>Rom\u00e1n Alberto Cepeda Gonz\u00e1lez reitera compromiso con estudiantes universitarios<\/strong>"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 04 de noviembre de 2022.<\/p>\n\n\n\n<p>El alcalde de Torre\u00f3n, Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, manifest\u00f3 el compromiso que tiene su Gobierno con los universitarios para crear las condiciones que les permitan desarrollarse profesionalmente una vez concluidos sus estudios, lo anterior lo expres\u00f3 durante la ceremonia de celebraci\u00f3n con motivo del 20 aniversario de la Ciudad Universitaria de la UAdeC, Unidad Torre\u00f3n.<\/p>\n\n\n\n<p>El Presidente Municipal dijo que le toca a su Gobierno y a cada uno de los presentes, desde su trinchera generar las condiciones, credibilidad y confianza, para que los j\u00f3venes estudiantes puedan cristalizar sus sue\u00f1os, adem\u00e1s reconoci\u00f3 la labor de aquellos que hicieron posible hace 20 a\u00f1os la construcci\u00f3n del complejo educativo.<\/p>\n\n\n\n<p>\u201cEs importante la educaci\u00f3n para Torre\u00f3n, para La Laguna, para Coahuila y para M\u00e9xico, y particularmente para mi Administraci\u00f3n, por eso justamente hemos creado el Instituto Municipal de Emprendimiento\u201d, coment\u00f3.<\/p>\n\n\n\n<p>Cepeda Gonz\u00e1lez mencion\u00f3 que Torre\u00f3n es el municipio con mayor n\u00famero de universidades per c\u00e1pita del pa\u00eds, por lo que dijo asume con responsabilidad el tener una ciudad que pueda recibir alumnos de otras partes de la rep\u00fablica.<\/p>\n\n\n\n<p><a>Por su parte Jes\u00fas Salvador Hern\u00e1ndez <\/a>V\u00e9lez, Rector de la Universidad Aut\u00f3noma de Coahuila, se\u00f1al\u00f3 que la construcci\u00f3n de la Ciudad Universitaria era indispensable para enfrentar los desaf\u00edos que el reciente siglo planteaba para la educaci\u00f3n.<\/p>\n\n\n\n<p>\u201cHan pasado dos d\u00e9cadas y hoy celebramos las acciones emprendidas en aquel tiempo por las autoridades universitarias enalteciendo las expresiones de apoyo y de buena voluntad que surgieron de los distintos niveles de gobierno, as\u00ed como de los diferentes sectores de la sociedad ante un proyecto de infraestructura sin precedentes\u201d dijo en su mensaje.<\/p>\n\n\n\n<p>Dijo que la construcci\u00f3n del complejo fue posible gracias a que en ese entonces exist\u00edan bolsas de recursos federales, para este tipo de obras<\/p>\n\n\n\n<p>\u201cAntes de esta Administraci\u00f3n Federal se manejaba una bolsa de 112 mil millones de pesos para infraestructura de las instituciones de educaci\u00f3n superior del pa\u00eds, hoy esa bolsa solo tiene 110 millones de pesos\u201d lament\u00f3 el rector.<\/p>\n\n\n\n<p>Sandra L\u00f3pez Chavarr\u00eda, Coordinadora de la Unidad Torre\u00f3n, dijo que es fundamental mostrarles a los j\u00f3venes alumnos, qui\u00e9nes fueron las personas responsables de darle forma al sue\u00f1o de tener instalaciones como las de CU.<\/p>\n\n\n\n<p>\u201cQueremos que sepan que en esta universidad trabajamos para ellos desde diferentes trincheras, que so\u00f1amos con brindarles aulas, auditorios, laboratorios, espacios deportivos y culturales para su desarrollo\u201d, expres\u00f3<\/p>\n\n\n\n<p>Reconoci\u00f3 la labor de gesti\u00f3n del rector Jes\u00fas Salvador Hern\u00e1ndez V\u00e9lez, quien a pesar de las dificultades en materia de presupuesto y recursos por parte del Gobierno Federal, ha mantenido las instalaciones en excelentes condiciones.<\/p>\n\n\n\n<p>Durante la ceremonia se reconoci\u00f3 a Manuel Medina Elizondo, Alberto Galv\u00e1n Tamayo, Oscar Fernando Gosserez Torres, Juan Antonio Ram\u00edrez Pons, Roberto Guti\u00e9rrez Tapia, Armando Nicolas Moreno Ju\u00e1rez, Edgardo Mart\u00ednez de Santiago, Alejandro Vladimir Hern\u00e1ndez Garc\u00eda, Ricardo G\u00e1lvez, Jes\u00fas Armando Tovar Rend\u00f3n, Norma Margarita Mendoza G\u00f3mez, Rene Mata Mac\u00edas y Rub\u00e9n Ram\u00edrez Rangel responsables de la edificaci\u00f3n de CU hace 20 a\u00f1os.<\/p>\n\n\n\n<p><em>&#8211;&nbsp; Torre\u00f3n \u00a1Siempre Puede! &#8211;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 04 de noviembre de 2022. El alcalde de Torre\u00f3n, Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, manifest\u00f3 el compromiso que tiene su Gobierno con los universitarios para crear las condiciones que les permitan desarrollarse profesionalmente una vez concluidos sus estudios, lo anterior lo expres\u00f3 durante la ceremonia de celebraci\u00f3n con motivo del 20 aniversario de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,14],"tags":[],"_links":{"self":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7115"}],"collection":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7115"}],"version-history":[{"count":1,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7115\/revisions"}],"predecessor-version":[{"id":7118,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7115\/revisions\/7118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media\/7117"}],"wp:attachment":[{"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaprogreso.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}